{"id":82463,"date":"2022-12-06T11:00:35","date_gmt":"2022-12-06T10:00:35","guid":{"rendered":"https:\/\/nextcloud.com\/blog\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\/"},"modified":"2025-11-03T13:08:08","modified_gmt":"2025-11-03T12:08:08","slug":"a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega","status":"publish","type":"post","link":"https:\/\/nextcloud.com\/it\/blog\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\/","title":{"rendered":"5 funzioni di Nextcloud Talk che non conosceva"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Conosce <a href=\"https:\/\/nextcloud.com\/it\/talk\/\">Nextcloud Talk<\/a> per le videochiamate, le chat con i colleghi e le conferenze web. Ma sapeva che..:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">1. I link si trasformano in widget<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nelle chat di Talk, i link inviati si trasformano istantaneamente in widget che forniscono una visione completa di ci\u00f2 che ha inviato. Pu\u00f2 trattarsi di anteprime di pagine web, video, documenti, carte Deck e altro ancora. Sono molto pi\u00f9 delicati per l&#8217;occhio e si fanno notare, in modo da non perdere mai pi\u00f9 un collegamento o un compito.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/11\/deck-card-in-talk.png\"><img decoding=\"async\" width=\"1024\" height=\"558\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/11\/deck-card-in-talk-1024x558.png\" alt=\"\" class=\"wp-image-79432\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/deck-card-in-talk-1024x558.png 1024w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/deck-card-in-talk-300x164.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/deck-card-in-talk-768x419.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/deck-card-in-talk-1536x838.png 1536w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/deck-card-in-talk-2048x1117.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n<section class=\"promo-section   full-width \" id=\"\" style=\"\" data-expiration=\"\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"text-block\">\n\t\t\t\t\t<p>Guardi la registrazione di questo webinar per scoprire tutto il potenziale di Nextcloud Talk!<\/p>\n<a class=\"c-btn btn-white\" href=\"https:\/\/nextcloud.com\/blog\/event\/overview-of-nextcloud-talk\/\" target=\"_self\">Guardi questo webinar<\/a>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<h2 class=\"wp-block-heading\">2. Creare un sondaggio nella chat<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pu\u00f2 creare un sondaggio direttamente nella messaggistica di Talk!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In una chat di gruppo, clicchi semplicemente sulla graffetta a sinistra della barra della chat e trovi l&#8217;opzione &#8220;crea nuovo sondaggio&#8221;. Crei una domanda e aggiunga tutte le risposte che desidera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Idee per i sondaggi:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Chieda come sta andando la giornata del suo team \ud83c\udf1e<\/li>\n\n\n\n<li>Chieda quando il suo team pu\u00f2 organizzare una cena natalizia \ud83c\udf7d\ufe0f<\/li>\n\n\n\n<li>Chieda quando \u00e8 meglio riprogrammare una chiamata di squadra \ud83d\udcde<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">I sondaggi sono un ottimo modo per interagire con il suo team e ottenere risultati rapidi per prendere decisioni su base giornaliera!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/10\/create-poll.png\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/10\/create-poll-1024x576.png\" alt=\"\" class=\"wp-image-64795\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/create-poll-1024x576.png 1024w, https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/create-poll-300x169.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/create-poll-768x432.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/create-poll-1536x864.png 1536w, https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/create-poll-2048x1152.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/10\/vote-in-poll.png\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/10\/vote-in-poll-1024x576.png\" alt=\"\" class=\"wp-image-64800\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/vote-in-poll-1024x576.png 1024w, https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/vote-in-poll-300x169.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/vote-in-poll-768x432.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/vote-in-poll-1536x864.png 1536w, https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/vote-in-poll-2048x1152.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n<div class=\"wp-block-image text-center\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/12\/poll.gif\"><img decoding=\"async\" width=\"399\" height=\"499\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/12\/poll.gif\" alt=\"\" class=\"wp-image-82407\"\/><\/a><\/figure>\n<\/div>\n\n<section class=\"promo-section   full-width \" id=\"\" style=\"\" data-expiration=\"\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"text-block\">\n\t\t\t\t\t<p>Guardi questo webinar e acquisisca preziose informazioni sulle varie funzioni di Nextcloud Talk che possono essere utili al suo team.<\/p>\n<a class=\"c-btn btn-white\" href=\"https:\/\/nextcloud.com\/blog\/event\/overview-of-nextcloud-talk\/\" target=\"_self\">Guardi questo webinar<\/a>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<h2 class=\"wp-block-heading\">3. Opzioni di benessere digitale \ud83c\udff5\ufe0f<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nella realt\u00e0 digitale di oggi, ci sono innumerevoli distrazioni che arrivano da tutte le direzioni e che la distolgono dal lavoro effettivo che deve svolgere, oltre a creare un ambiente di lavoro opprimente. Tenendo presente la sua salute mentale, abbiamo alcune opzioni per lei:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Selezionare le notifiche di chiamata<\/strong> &#8211; Se desidera avviare una chiamata all&#8217;interno di una grande chat di gruppo ma deve notificare solo alcune persone, pu\u00f2 selezionare i partecipanti individualmente e inviare loro una notifica di chiamata. In questo modo si evita di disturbare gli altri che non hanno bisogno di unirsi.<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/10\/call-notification.png\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/10\/call-notification-1024x576.png\" alt=\"\" class=\"wp-image-64810\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/call-notification-1024x576.png 1024w, https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/call-notification-300x169.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/call-notification-768x432.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/call-notification-1536x864.png 1536w, https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/call-notification-2048x1152.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">2<strong>. Inviare un messaggio senza notifica<\/strong> &#8211; A volte i messaggi non sono urgenti e lei non vuole disturbare un collega.. <\/p>\n\n\n<div class=\"wp-block-image text-center\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/12\/silent-send.gif\"><img decoding=\"async\" width=\"845\" height=\"187\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/12\/silent-send.gif\" alt=\"\" class=\"wp-image-82415\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">3. \u26d4 <strong>Pulsante &#8220;non disturbare&#8221;<\/strong>\u26d4 &#8211; Tutti hanno bisogno di uno di questi! Nelle impostazioni di Nextcloud, attivi automaticamente l&#8217;opzione &#8220;non disturbare&#8221; al di fuori degli orari di lavoro da lei scelti. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/11\/do-not-disturb.png\"><img decoding=\"async\" width=\"1024\" height=\"554\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/11\/do-not-disturb-1024x554.png\" alt=\"\" class=\"wp-image-79452\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/do-not-disturb-1024x554.png 1024w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/do-not-disturb-300x162.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/do-not-disturb-768x416.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/do-not-disturb-1536x832.png 1536w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/do-not-disturb-2048x1109.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n<section class=\"promo-section   full-width \" id=\"\" style=\"\" data-expiration=\"\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"text-block\">\n\t\t\t\t\t<p>Sblocca la potenza di Nextcloud Talk con la registrazione di questo imperdibile webinar!<\/p>\n<a class=\"c-btn btn-white\" href=\"https:\/\/nextcloud.com\/blog\/event\/overview-of-nextcloud-talk\/\" target=\"_self\">Guardi questo webinar<\/a>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<h2 class=\"wp-block-heading\">4. Scadenza per i messaggi di chat<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nelle impostazioni della sua chat Talk, pu\u00f2 attivare la scadenza dei messaggi per 1 ora, 8 ore, 1 giorno, 1 settimana o 4 settimane. Questa \u00e8 un&#8217;ottima opzione se desidera che tutti i messaggi di una chat vengano eliminati dopo un certo periodo di tempo:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udd0f Conversazioni riservate<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udf1e Conversazioni quotidiane e informali che non sono importanti<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcfd\ufe0f Progetti a breve termine<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nel complesso, l&#8217;opzione di scadenza dei messaggi agisce come una pulizia &#8220;automatica&#8221; per i messaggi in una chat, tuttavia pu\u00f2 sempre scegliere di eliminare manualmente interi messaggi o di cancellare la chat stessa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/11\/message-exp.png\"><img decoding=\"async\" width=\"1024\" height=\"556\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/11\/message-exp-1024x556.png\" alt=\"\" class=\"wp-image-80230\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/message-exp-1024x556.png 1024w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/message-exp-300x163.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/message-exp-768x417.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/message-exp-1536x833.png 1536w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/message-exp-2048x1111.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"316\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/11\/message-exp-2-1024x316.png\" alt=\"\" class=\"wp-image-80235\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/message-exp-2-1024x316.png 1024w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/message-exp-2-300x93.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/message-exp-2-768x237.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/message-exp-2-1536x475.png 1536w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/message-exp-2-2048x633.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">5. Si integra con Deck e Office<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Deck<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Poich\u00e9 Nextcloud \u00e8 una piattaforma di collaborazione all-in-one, il nostro obiettivo \u00e8 quello di integrare profondamente le nostre applicazioni tra loro, in modo che lei possa lavorare in modo pi\u00f9 efficiente in un unico luogo. Per esempio, se sta lavorando in Deck e vuole condividere una scheda con un collega in quel momento, \u00e8 sufficiente cliccare su &#8220;invia a una conversazione&#8221; e la scheda verr\u00e0 immediatamente inviata a una chat Talk di sua scelta e visualizzata come widget.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/11\/post-deck-card-to-convo.png\"><img decoding=\"async\" width=\"592\" height=\"576\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/11\/post-deck-card-to-convo-592x576.png\" alt=\"\" class=\"wp-image-79439\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/post-deck-card-to-convo-592x576.png 592w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/post-deck-card-to-convo-300x292.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/post-deck-card-to-convo-768x747.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/post-deck-card-to-convo-1536x1494.png 1536w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/post-deck-card-to-convo.png 1606w\" sizes=\"(max-width: 592px) 100vw, 592px\" \/><\/a><\/figure>\n<\/div>\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"558\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/11\/deck-card-in-talk-1024x558.png\" alt=\"\" class=\"wp-image-79432\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/deck-card-in-talk-1024x558.png 1024w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/deck-card-in-talk-300x164.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/deck-card-in-talk-768x419.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/deck-card-in-talk-1536x838.png 1536w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/deck-card-in-talk-2048x1117.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Office<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Sapeva che pu\u00f2 creare un nuovo file, un foglio di calcolo o una presentazione direttamente nella sua chat?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diciamo che sta messaggiando con il suo manager che sta parlando di una nuova strategia e le viene una grande idea. Prima di dimenticare il suo pensiero, apra rapidamente un nuovo file di testo all&#8217;interno della sua chat e annoti le sue note. Efficiente e semplice.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"554\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/11\/new-doc-1024x554.png\" alt=\"\" class=\"wp-image-79459\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/new-doc-1024x554.png 1024w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/new-doc-300x162.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/new-doc-768x416.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/new-doc-1536x832.png 1536w, https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/new-doc-2048x1109.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Tutte le novit\u00e0 di Talk in Nextcloud Hub 3!<\/h2>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Nextcloud Talk improvements [Hub 3]\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/qKB072Oxdlc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<section class=\"events-section gr\" id=\"\">\n\t<div class=\"container\">\n\t\t<div class=\"row justify-content-center\">\n\t\t\t<div class=\"col-lg-10\">\n\t\t\t\t<div class=\"section-title\">\n\t\t\t\t\t<h2>Vota Nextcloud Talk!<\/h2><p>Ci piacerebbe conoscere il suo feedback su Nextcloud Talk. <\/p>\n<p>\u00c8 un ottimo modo per contribuire e diffondere la parola.<\/p>\n<p>Ci valuti oggi stesso sulle migliori piattaforme di valutazione!<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/section>\n\n\n<div class=\"wp-block-group nc_row_ratings is-nowrap is-layout-flex wp-container-core-group-is-layout-8f761849 wp-block-group-is-layout-flex\">\n<a target=\"_blank\" href=\"https:\/\/www.capterra.com\/reviews\/161572\/NextCloud?utm_source=vendor&#038;utm_medium=badge&#038;utm_campaign=capterra_reviews_badge\" rel=\"noopener\"> <img decoding=\"async\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2023\/02\/capterra.svg\" border=\"0\"\/> <\/a>\n\n\n\n<a href=\"https:\/\/www.getapp.com\/collaboration-software\/a\/nextcloud\/reviews\/\" target=\"_blank\" rel=\"noopener\"> <img decoding=\"async\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2023\/02\/getapp.png\" border=\"0\"\/> <\/a>\n\n\n\n<a target=\"_blank\" href=\"https:\/\/www.softwareadvice.com\/file-sharing\/nextcloud-profile\/reviews\/\" rel=\"noopener\"> <img decoding=\"async\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2024\/07\/software_advice.png\" border=\"0\"\/> <\/a>\n\n\n\n<!-- Begin SF Tag -->\n<div class=\"sf-root\" data-id=\"2973658\" data-badge=\"trusted-vendor-black\" data-variant-id=\"sf\" style=\"width:200px\">\n    <a href=\"https:\/\/sourceforge.net\/software\/product\/NextCloud\/\" target=\"_blank\" rel=\"noopener\">\n<img decoding=\"async\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/source-forge-logo.svg\"><\/a>\n<\/div>\n\n\n\n<a title=\"Les utilisateurs aiment Nextcloud sur G2\" href=\"https:\/\/www.g2.com\/products\/nextcloud\/reviews?utm_source=rewards-badge\"><img decoding=\"async\" style=\"width: 125px;\" alt=\"Users love Nextcloud on G2\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/g2-logo.svg\"\/><\/a><script>(function(a,b,c,d){window.fetch(\"https:\/\/www.g2.com\/products\/nextcloud\/rating_schema.json\").then(e=>e.json()).then(f=>{c=a.createElement(b);c.type=\"application\/ld+json\";c.text=JSON.stringify(f);d=a.getElementsByTagName(b)[0];d.parentNode.insertBefore(c,d);});})(document,\"script\");<\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Conosce Nextcloud Talk per le videochiamate, le chat con i colleghi e le conferenze web. Ma sapeva che..: 1. I link si trasformano in widget Nelle chat di Talk, i link inviati si trasformano istantaneamente in widget che forniscono una visione completa di ci\u00f2 che ha inviato. Pu\u00f2 trattarsi di anteprime di pagine web, video, [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"publish_to_discourse":"","publish_post_category":"22","wpdc_auto_publish_overridden":"1","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"405240","discourse_permalink":"https:\/\/help.nextcloud.com\/t\/5-funzioni-di-nextcloud-talk-che-non-conosceva\/151360","wpdc_publishing_response":"success","wpdc_publishing_error":"","footnotes":""},"categories":[252,234,233],"tags":[],"class_list":["post-82463","post","type-post","status-publish","format-standard","hentry","category-app-tuesday-it","category-blog-it","category-comunita"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5 funzioni di Nextcloud Talk che non conosceva - Nextcloud<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nextcloud.com\/it\/blog\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 funzioni di Nextcloud Talk che non conosceva - Nextcloud\" \/>\n<meta property=\"og:description\" content=\"Conosce Nextcloud Talk per le videochiamate, le chat con i colleghi e le conferenze web. Ma sapeva che..: 1. I link si trasformano in widget Nelle chat di Talk, i link inviati si trasformano istantaneamente in widget che forniscono una visione completa di ci\u00f2 che ha inviato. Pu\u00f2 trattarsi di anteprime di pagine web, video, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nextcloud.com\/it\/blog\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\/\" \/>\n<meta property=\"og:site_name\" content=\"Nextcloud\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nextclouders\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-06T10:00:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-03T12:08:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/deck-card-in-talk.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2872\" \/>\n\t<meta property=\"og:image:height\" content=\"1566\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mikaela Schneider\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mikaela Schneider\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/blog\\\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/blog\\\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\\\/\"},\"author\":{\"name\":\"Mikaela Schneider\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/#\\\/schema\\\/person\\\/ea95df24e6e3adc5f63c79555fa599f5\"},\"headline\":\"5 funzioni di Nextcloud Talk che non conosceva\",\"datePublished\":\"2022-12-06T10:00:35+00:00\",\"dateModified\":\"2025-11-03T12:08:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/blog\\\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\\\/\"},\"wordCount\":595,\"publisher\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/blog\\\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nextcloud.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/deck-card-in-talk-1024x558.png\",\"articleSection\":[\"App Tuesday\",\"Blog\",\"Comunit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/blog\\\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\\\/\",\"url\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/blog\\\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\\\/\",\"name\":\"5 funzioni di Nextcloud Talk che non conosceva - Nextcloud\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/blog\\\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/blog\\\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nextcloud.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/deck-card-in-talk-1024x558.png\",\"datePublished\":\"2022-12-06T10:00:35+00:00\",\"dateModified\":\"2025-11-03T12:08:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/blog\\\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nextcloud.com\\\/it\\\/blog\\\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/blog\\\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nextcloud.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/deck-card-in-talk-1024x558.png\",\"contentUrl\":\"https:\\\/\\\/nextcloud.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/deck-card-in-talk-1024x558.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/blog\\\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 funzioni di Nextcloud Talk che non conosceva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/\",\"name\":\"Nextcloud\",\"description\":\"Regain control over your data\",\"publisher\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/#organization\",\"name\":\"Nextcloud\",\"url\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nextcloud.com\\\/c\\\/uploads\\\/2022\\\/10\\\/nextcloud-logo-blue-transparent.svg\",\"contentUrl\":\"https:\\\/\\\/nextcloud.com\\\/c\\\/uploads\\\/2022\\\/10\\\/nextcloud-logo-blue-transparent.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Nextcloud\"},\"image\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nextclouders\\\/\",\"https:\\\/\\\/x.com\\\/nextclouders\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/10827569\\\/\",\"https:\\\/\\\/youtube.com\\\/nextcloud\",\"https:\\\/\\\/www.instagram.com\\\/nextclouders\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/it\\\/#\\\/schema\\\/person\\\/ea95df24e6e3adc5f63c79555fa599f5\",\"name\":\"Mikaela Schneider\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g\",\"caption\":\"Mikaela Schneider\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 funzioni di Nextcloud Talk che non conosceva - Nextcloud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nextcloud.com\/it\/blog\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\/","og_locale":"it_IT","og_type":"article","og_title":"5 funzioni di Nextcloud Talk che non conosceva - Nextcloud","og_description":"Conosce Nextcloud Talk per le videochiamate, le chat con i colleghi e le conferenze web. Ma sapeva che..: 1. I link si trasformano in widget Nelle chat di Talk, i link inviati si trasformano istantaneamente in widget che forniscono una visione completa di ci\u00f2 che ha inviato. Pu\u00f2 trattarsi di anteprime di pagine web, video, [&hellip;]","og_url":"https:\/\/nextcloud.com\/it\/blog\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\/","og_site_name":"Nextcloud","article_publisher":"https:\/\/www.facebook.com\/Nextclouders\/","article_published_time":"2022-12-06T10:00:35+00:00","article_modified_time":"2025-11-03T12:08:08+00:00","og_image":[{"width":2872,"height":1566,"url":"https:\/\/nextcloud.com\/c\/uploads\/2022\/11\/deck-card-in-talk.png","type":"image\/png"}],"author":"Mikaela Schneider","twitter_misc":{"Scritto da":"Mikaela Schneider","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nextcloud.com\/it\/blog\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\/#article","isPartOf":{"@id":"https:\/\/nextcloud.com\/it\/blog\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\/"},"author":{"name":"Mikaela Schneider","@id":"https:\/\/nextcloud.com\/it\/#\/schema\/person\/ea95df24e6e3adc5f63c79555fa599f5"},"headline":"5 funzioni di Nextcloud Talk che non conosceva","datePublished":"2022-12-06T10:00:35+00:00","dateModified":"2025-11-03T12:08:08+00:00","mainEntityOfPage":{"@id":"https:\/\/nextcloud.com\/it\/blog\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\/"},"wordCount":595,"publisher":{"@id":"https:\/\/nextcloud.com\/it\/#organization"},"image":{"@id":"https:\/\/nextcloud.com\/it\/blog\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\/#primaryimage"},"thumbnailUrl":"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/11\/deck-card-in-talk-1024x558.png","articleSection":["App Tuesday","Blog","Comunit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/nextcloud.com\/it\/blog\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\/","url":"https:\/\/nextcloud.com\/it\/blog\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\/","name":"5 funzioni di Nextcloud Talk che non conosceva - Nextcloud","isPartOf":{"@id":"https:\/\/nextcloud.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nextcloud.com\/it\/blog\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\/#primaryimage"},"image":{"@id":"https:\/\/nextcloud.com\/it\/blog\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\/#primaryimage"},"thumbnailUrl":"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/11\/deck-card-in-talk-1024x558.png","datePublished":"2022-12-06T10:00:35+00:00","dateModified":"2025-11-03T12:08:08+00:00","breadcrumb":{"@id":"https:\/\/nextcloud.com\/it\/blog\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nextcloud.com\/it\/blog\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nextcloud.com\/it\/blog\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\/#primaryimage","url":"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/11\/deck-card-in-talk-1024x558.png","contentUrl":"https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/11\/deck-card-in-talk-1024x558.png"},{"@type":"BreadcrumbList","@id":"https:\/\/nextcloud.com\/it\/blog\/a-volte-i-messaggi-non-sono-urgenti-e-non-vuole-disturbare-un-collega\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nextcloud.com\/it\/"},{"@type":"ListItem","position":2,"name":"5 funzioni di Nextcloud Talk che non conosceva"}]},{"@type":"WebSite","@id":"https:\/\/nextcloud.com\/it\/#website","url":"https:\/\/nextcloud.com\/it\/","name":"Nextcloud","description":"Regain control over your data","publisher":{"@id":"https:\/\/nextcloud.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nextcloud.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/nextcloud.com\/it\/#organization","name":"Nextcloud","url":"https:\/\/nextcloud.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nextcloud.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","contentUrl":"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","width":"1024","height":"1024","caption":"Nextcloud"},"image":{"@id":"https:\/\/nextcloud.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Nextclouders\/","https:\/\/x.com\/nextclouders","https:\/\/www.linkedin.com\/company\/10827569\/","https:\/\/youtube.com\/nextcloud","https:\/\/www.instagram.com\/nextclouders\/"]},{"@type":"Person","@id":"https:\/\/nextcloud.com\/it\/#\/schema\/person\/ea95df24e6e3adc5f63c79555fa599f5","name":"Mikaela Schneider","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g","caption":"Mikaela Schneider"}}]}},"featured_media_url":false,"_links":{"self":[{"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/posts\/82463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/comments?post=82463"}],"version-history":[{"count":1,"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/posts\/82463\/revisions"}],"predecessor-version":[{"id":348272,"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/posts\/82463\/revisions\/348272"}],"wp:attachment":[{"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/media?parent=82463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/categories?post=82463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/tags?post=82463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}