{"id":5833,"date":"2019-04-25T08:46:49","date_gmt":"2019-04-25T08:46:49","guid":{"rendered":"https:\/\/nextcloud.com\/?p=5833"},"modified":"2019-04-25T08:46:49","modified_gmt":"2019-04-25T08:46:49","slug":"nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers","status":"publish","type":"post","link":"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/","title":{"rendered":"Nextcloud 16 implements Access Control Lists to replace classic File Servers"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignright size-thumbnail\" src=\"https:\/\/nextcloud.com\/media\/16-small.png\" alt=\"Nc 16 logo\"><\/p>\n<p>While Nextcloud is often used in companies to replace aging &#8216;shared folder&#8217; solutions like a Windows Network Drive, the sharing model modern Dropbox-like solutions use is very different. Rather than a single, fixed folder structure available to all users and tightly controlled by IT, users have their own view on their data and can share files and folders at will with others, who will receive shared files in their home file view.<\/p>\n<p>As this release brings so many improvements, we&#8217;ve written 4 other blogs with more details about the main features:<\/p>\n<ul>\n<li><a href=\"https:\/\/nextcloud.com\/blog\/nextcloud-16-introduces-machine-learning-based-security-and-usability-features-acl-permissions-and-cross-app-projects\/\">Nextcloud 16 introduces machine learning based security and usability features, ACL permissions and cross-app projects<\/a><\/li>\n<li><a href=\"https:\/\/nextcloud.com\/blog\/nextcloud-16-becomes-smarter-with-machine-learning-for-security-and-productivity\/\">Nextcloud 16 becomes smarter with Machine Learning for security and productivity<\/a><\/li>\n<li><a href=\"https:\/\/nextcloud.com\/blog\/nextcloud-16-allows-you-to-link-resources-to-keep-track-of-your-projects\/\">Nextcloud 16 allows you to link resources to keep track of your projects<\/a><\/li>\n<li><a href=\"https:\/\/nextcloud.com\/blog\/talk-6.0-brings-commands-improved-user-experience-and-more\/\">Talk 6.0 brings commands, improved user experience and more<\/a><\/li>\n<\/ul>\n<p><a target=\"_blank\" href=\"https:\/\/nextcloud.com\/media\/ACLs_in_groupfolders_sidebar.png\" rel=\"noopener\"><img decoding=\"async\"  class=\"img-responsive\" alt=\"ACLs in sidebar\" src=\"https:\/\/nextcloud.com\/media\/ACLs_in_groupfolders_sidebar_tiny_crop.png\" \/><\/a><\/p>\n<h2>The old and new ways of sharing<\/h2>\n<p>A major difference between the folder tree ruled by system administrators and the user-centric view is the use of access control lists (ACL&#8217;s) in the &#8216;old&#8217; world. These allow an admin to share a folder with all users while changing the access rights on sub folders and folders in those folders and so on. This makes it possible to have read-only access to a top folder, write access to a sub folder, read-only to a folder in there again and so on. Nextcloud can give users access to a Windows Network Drive as external storage and respects these ACL&#8217;s, but does not otherwise expose them for manipulation.<\/p>\n<p>Nextcloud 16 introduces support for ACL&#8217;s in group folders. System administrators can set, on every file and (sub)folder in a group share, specific access rights. These are inherited by default, so a &#8216;no write access&#8217; for a specific user or group will apply to all files and sub folders, unless overridden again by the system administrator.<\/p>\n<p>Available for configuration are Read, Write, Create, Delete and Share permissions, each of which can be set to &#8216;inherit&#8217;, &#8216;allow&#8217; or &#8216;deny&#8217; for each user or group for each file and (sub)folder in a group share.<\/p>\n<h2>How it works<\/h2>\n<p>To set up a group folder with ACL&#8217;s, the administrator enables the Group Folders app, creates a group folder and selects the groups who should have access to it. Make sure the admin who has to set up the permissions is included. Then, enable the &#8216;advanced permissions&#8217; setting.<\/p>\n<p><img decoding=\"async\" class=\"overlay-trigger banner\" alt=\"Creating ACLs\" src=\"https:\/\/nextcloud.com\/media\/ACLs_in_groupfolders_create_crop.png\" \/><\/p>\n<p>In the Files app, go to the group folder and look at the sharing view. There will be a group folder permissions view, where you can specify permissions. Use the &#8216;Add advanced permission rule&#8217; button to add a rule.<\/p>\n<p><img decoding=\"async\" class=\"overlay-trigger banner\" alt=\"ACLs in sidebar\" src=\"https:\/\/nextcloud.com\/media\/ACLs_in_groupfolders_add_permission_rule_crop.png\" \/><\/p>\n<p>You now pick from a list of all groups and users who have access to the group folder and can then set the fine-grained permissions. Note that &#8216;inherit&#8217; is default, and by removing the rule with the &#8216;x&#8217; on the right you can return to the permissions inherited from the parent folder. <\/p>\n<p><img decoding=\"async\" class=\"overlay-trigger banner\" alt=\"ACLs in sidebar\" src=\"https:\/\/nextcloud.com\/media\/ACLs_in_groupfolders_sidebar_crop.png\" \/><\/p>\n<p>Users can see what their rights are, but not modify them.<\/p>\n<p><img decoding=\"async\" class=\"overlay-trigger banner\" alt=\"ACLs in sidebar\" src=\"https:\/\/nextcloud.com\/media\/ACLs_in_groupfolders_user_view_crop.png\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>While Nextcloud is often used in companies to replace aging &#8216;shared folder&#8217; solutions like a Windows Network Drive, the sharing model modern Dropbox-like solutions use is very different. Rather than a single, fixed folder structure available to all users and tightly controlled by IT, users have their own view on their data and can share [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5899,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"publish_to_discourse":"0","publish_post_category":"22","wpdc_auto_publish_overridden":"1","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"149592","discourse_permalink":"https:\/\/help.nextcloud.com\/t\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/52180","wpdc_publishing_response":"","wpdc_publishing_error":"","footnotes":""},"categories":[7,19,14],"tags":[],"class_list":["post-5833","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-pressrelease","category-release"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nextcloud 16 implements Access Control Lists to replace classic File Servers - Nextcloud<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nextcloud 16 implements Access Control Lists to replace classic File Servers - Nextcloud\" \/>\n<meta property=\"og:description\" content=\"While Nextcloud is often used in companies to replace aging &#8216;shared folder&#8217; solutions like a Windows Network Drive, the sharing model modern Dropbox-like solutions use is very different. Rather than a single, fixed folder structure available to all users and tightly controlled by IT, users have their own view on their data and can share [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/\" \/>\n<meta property=\"og:site_name\" content=\"Nextcloud\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nextclouders\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-25T08:46:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2019\/04\/ACLs_in_groupfolders_user_view.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2600\" \/>\n\t<meta property=\"og:image:height\" content=\"1480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jos Poortvliet\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jos Poortvliet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/\"},\"author\":{\"name\":\"Jos Poortvliet\",\"@id\":\"https:\/\/nextcloud.com\/it\/#\/schema\/person\/c3c1a52fbc1c6a2be2f1df8818daa8c2\"},\"headline\":\"Nextcloud 16 implements Access Control Lists to replace classic File Servers\",\"datePublished\":\"2019-04-25T08:46:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/\"},\"wordCount\":509,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nextcloud.com\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nextcloud.com\/c\/uploads\/2019\/04\/ACLs_in_groupfolders_user_view.png\",\"articleSection\":[\"News\",\"Press release\",\"Release\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/\",\"url\":\"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/\",\"name\":\"Nextcloud 16 implements Access Control Lists to replace classic File Servers - Nextcloud\",\"isPartOf\":{\"@id\":\"https:\/\/nextcloud.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nextcloud.com\/c\/uploads\/2019\/04\/ACLs_in_groupfolders_user_view.png\",\"datePublished\":\"2019-04-25T08:46:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/#primaryimage\",\"url\":\"https:\/\/nextcloud.com\/c\/uploads\/2019\/04\/ACLs_in_groupfolders_user_view.png\",\"contentUrl\":\"https:\/\/nextcloud.com\/c\/uploads\/2019\/04\/ACLs_in_groupfolders_user_view.png\",\"width\":2600,\"height\":1480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nextcloud.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nextcloud 16 implements Access Control Lists to replace classic File Servers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nextcloud.com\/it\/#website\",\"url\":\"https:\/\/nextcloud.com\/it\/\",\"name\":\"Nextcloud\",\"description\":\"Regain control over your data\",\"publisher\":{\"@id\":\"https:\/\/nextcloud.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nextcloud.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nextcloud.com\/it\/#organization\",\"name\":\"Nextcloud\",\"url\":\"https:\/\/nextcloud.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/nextcloud.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg\",\"contentUrl\":\"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Nextcloud\"},\"image\":{\"@id\":\"https:\/\/nextcloud.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Nextclouders\/\",\"https:\/\/x.com\/nextclouders\",\"https:\/\/www.linkedin.com\/company\/10827569\/\",\"https:\/\/youtube.com\/nextcloud\",\"https:\/\/www.instagram.com\/nextclouders\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nextcloud.com\/it\/#\/schema\/person\/c3c1a52fbc1c6a2be2f1df8818daa8c2\",\"name\":\"Jos Poortvliet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/nextcloud.com\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1c6de64891ee8c4902e1ac198f26ea5fb202d8bbaa7bce35b6a184610bbe4a3d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1c6de64891ee8c4902e1ac198f26ea5fb202d8bbaa7bce35b6a184610bbe4a3d?s=96&d=mm&r=g\",\"caption\":\"Jos Poortvliet\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nextcloud 16 implements Access Control Lists to replace classic File Servers - Nextcloud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/","og_locale":"it_IT","og_type":"article","og_title":"Nextcloud 16 implements Access Control Lists to replace classic File Servers - Nextcloud","og_description":"While Nextcloud is often used in companies to replace aging &#8216;shared folder&#8217; solutions like a Windows Network Drive, the sharing model modern Dropbox-like solutions use is very different. Rather than a single, fixed folder structure available to all users and tightly controlled by IT, users have their own view on their data and can share [&hellip;]","og_url":"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/","og_site_name":"Nextcloud","article_publisher":"https:\/\/www.facebook.com\/Nextclouders\/","article_published_time":"2019-04-25T08:46:49+00:00","og_image":[{"width":2600,"height":1480,"url":"https:\/\/nextcloud.com\/wp-content\/uploads\/2019\/04\/ACLs_in_groupfolders_user_view.png","type":"image\/png"}],"author":"Jos Poortvliet","twitter_misc":{"Scritto da":"Jos Poortvliet","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/#article","isPartOf":{"@id":"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/"},"author":{"name":"Jos Poortvliet","@id":"https:\/\/nextcloud.com\/it\/#\/schema\/person\/c3c1a52fbc1c6a2be2f1df8818daa8c2"},"headline":"Nextcloud 16 implements Access Control Lists to replace classic File Servers","datePublished":"2019-04-25T08:46:49+00:00","mainEntityOfPage":{"@id":"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/"},"wordCount":509,"commentCount":0,"publisher":{"@id":"https:\/\/nextcloud.com\/it\/#organization"},"image":{"@id":"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/#primaryimage"},"thumbnailUrl":"https:\/\/nextcloud.com\/c\/uploads\/2019\/04\/ACLs_in_groupfolders_user_view.png","articleSection":["News","Press release","Release"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/","url":"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/","name":"Nextcloud 16 implements Access Control Lists to replace classic File Servers - Nextcloud","isPartOf":{"@id":"https:\/\/nextcloud.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/#primaryimage"},"image":{"@id":"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/#primaryimage"},"thumbnailUrl":"https:\/\/nextcloud.com\/c\/uploads\/2019\/04\/ACLs_in_groupfolders_user_view.png","datePublished":"2019-04-25T08:46:49+00:00","breadcrumb":{"@id":"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/#primaryimage","url":"https:\/\/nextcloud.com\/c\/uploads\/2019\/04\/ACLs_in_groupfolders_user_view.png","contentUrl":"https:\/\/nextcloud.com\/c\/uploads\/2019\/04\/ACLs_in_groupfolders_user_view.png","width":2600,"height":1480},{"@type":"BreadcrumbList","@id":"https:\/\/nextcloud.com\/it\/blog\/nextcloud-16-implements-access-control-lists-to-replace-classic-file-servers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nextcloud.com\/it\/"},{"@type":"ListItem","position":2,"name":"Nextcloud 16 implements Access Control Lists to replace classic File Servers"}]},{"@type":"WebSite","@id":"https:\/\/nextcloud.com\/it\/#website","url":"https:\/\/nextcloud.com\/it\/","name":"Nextcloud","description":"Regain control over your data","publisher":{"@id":"https:\/\/nextcloud.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nextcloud.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/nextcloud.com\/it\/#organization","name":"Nextcloud","url":"https:\/\/nextcloud.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nextcloud.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","contentUrl":"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","width":"1024","height":"1024","caption":"Nextcloud"},"image":{"@id":"https:\/\/nextcloud.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Nextclouders\/","https:\/\/x.com\/nextclouders","https:\/\/www.linkedin.com\/company\/10827569\/","https:\/\/youtube.com\/nextcloud","https:\/\/www.instagram.com\/nextclouders\/"]},{"@type":"Person","@id":"https:\/\/nextcloud.com\/it\/#\/schema\/person\/c3c1a52fbc1c6a2be2f1df8818daa8c2","name":"Jos Poortvliet","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nextcloud.com\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1c6de64891ee8c4902e1ac198f26ea5fb202d8bbaa7bce35b6a184610bbe4a3d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c6de64891ee8c4902e1ac198f26ea5fb202d8bbaa7bce35b6a184610bbe4a3d?s=96&d=mm&r=g","caption":"Jos Poortvliet"}}]}},"featured_media_url":"https:\/\/nextcloud.com\/c\/uploads\/2019\/04\/ACLs_in_groupfolders_user_view.png","_links":{"self":[{"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/posts\/5833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/comments?post=5833"}],"version-history":[{"count":0,"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/posts\/5833\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/media\/5899"}],"wp:attachment":[{"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/media?parent=5833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/categories?post=5833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nextcloud.com\/it\/wp-json\/wp\/v2\/tags?post=5833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}