{"id":203296,"date":"2023-12-07T11:05:46","date_gmt":"2023-12-07T10:05:46","guid":{"rendered":"https:\/\/nextcloud.com\/blog\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\/"},"modified":"2024-03-07T11:25:01","modified_gmt":"2024-03-07T10:25:01","slug":"gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires","status":"publish","type":"post","link":"https:\/\/nextcloud.com\/fr\/blog\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\/","title":{"rendered":"Gardez vos donn\u00e9es dans votre institution \u00e9ducative : Utiliser Nextcloud localement dans les \u00e9tablissements scolaires et universitaires"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Qui d\u00e9tient les donn\u00e9es dans votre universit\u00e9 ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Qui d\u00e9tient les fichiers de votre \u00e9cole ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 qui appartiennent les donn\u00e9es des \u00e9l\u00e8ves ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La protection des donn\u00e9es dans les \u00e9coles, les universit\u00e9s et les autres \u00e9tablissements d&rsquo;enseignement est primordiale pour le bien des organisations et de leurs \u00e9tudiants. Les mesures de s\u00e9curit\u00e9 prot\u00e9geant les informations personnelles, la communication externe et le travail collaboratif doivent \u00eatre pr\u00e9serv\u00e9es int\u00e9gralement et en toute transparence.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/12\/Featured-Image-Template.png\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/12\/Featured-Image-Template-1024x576.png\" alt=\"\" class=\"wp-image-187172\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2023\/12\/Featured-Image-Template-1024x576.png 1024w, https:\/\/nextcloud.com\/c\/uploads\/2023\/12\/Featured-Image-Template-300x169.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2023\/12\/Featured-Image-Template-768x432.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2023\/12\/Featured-Image-Template-1536x864.png 1536w, https:\/\/nextcloud.com\/c\/uploads\/2023\/12\/Featured-Image-Template.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Avec Nextcloud Hub, les \u00e9tablissements \u00e9ducatifs peuvent facilement prot\u00e9ger leurs donn\u00e9es stock\u00e9es sur site afin de garantir une s\u00e9curit\u00e9 optimale. Voyons comment Nextcloud fonctionne pour les enseignants, les \u00e9tudiants et les chercheurs.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Confidentialit\u00e9 des donn\u00e9es et conformit\u00e9 pour le personnel enseignant<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les administrateurs scolaires et le personnel enseignant sont les garants de l&rsquo;avenir de leurs \u00e9l\u00e8ves et de la protection de leur vie priv\u00e9e. Les informations personnelles des \u00e9tudiants doivent \u00eatre prot\u00e9g\u00e9es et conserv\u00e9es dans les locaux de l&rsquo;\u00e9cole ou de l&rsquo;universit\u00e9. Nextcloud garantit une s\u00e9curit\u00e9 maximale afin que vous puissiez stocker, partager et archiver des fichiers en toute transparence et avec pr\u00e9cision.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab\u00a0Nous voulions offrir un service alternatif aux suites bureautiques de Google ou de Microsoft qui soit compatible avec notre politique de souverainet\u00e9 des donn\u00e9es\u00a0\u00bb.<\/p><cite>Sorbonne Universit\u00e9, \u00e9tude de cas<\/cite><\/blockquote><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Pour de nombreuses \u00e9coles et universit\u00e9s, la confidentialit\u00e9 et la conformit\u00e9 des donn\u00e9es peuvent \u00eatre difficiles \u00e0 assurer lorsqu&rsquo;elles utilisent des logiciels propri\u00e9taires. Avec Nextcloud, les \u00e9coles peuvent obtenir un h\u00e9bergement local des donn\u00e9es sur leur propre serveur et garder un contr\u00f4le total sur leur infrastructure informatique.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Apprentissage et collaboration \u00e0 distance des \u00e9tudiants<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;apprentissage des \u00e9tudiants est facilit\u00e9 lorsque les technologies qu&rsquo;ils utilisent sont fiables. Ils doivent \u00eatre en mesure de collaborer facilement avec d&rsquo;autres \u00e9tudiants, de travailler sur leurs devoirs et de soumettre des travaux et des projets. Nextcloud offre une plateforme intuitive que les \u00e9tudiants peuvent utiliser facilement et \u00e0 laquelle ils peuvent se connecter de n&rsquo;importe o\u00f9. En mati\u00e8re d&rsquo;apprentissage \u00e0 distance, Nextcloud est l\u00e0 pour \u00e7a :<\/p>\n\n\n\n<ul class=\"nc-list wp-block-list\">\n<li>Appels vid\u00e9o avec salles de r\u00e9union<\/li>\n\n\n\n<li>Edition en temps r\u00e9el des documents<\/li>\n\n\n\n<li>Tchat s\u00e9curis\u00e9 avec des camarades de classe et des enseignants<\/li>\n\n\n\n<li>Stockage de fichiers contr\u00f4l\u00e9 par l&rsquo;administrateur<\/li>\n\n\n\n<li>Int\u00e9grations avec les plateformes \u00e9lectroniques les plus courantes<\/li>\n\n\n\n<li>Acc\u00e8s \u00e0 partir d&rsquo;interfaces web, mobiles et ordinateurs de bureau<\/li>\n\n\n\n<li>Et bien plus encore !<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Quels que soient les besoins de votre \u00e9cole, universit\u00e9 ou institution, ils peuvent \u00eatre satisfaits par Nextcloud.<\/p>\n\n\n<section class=\"promo-section promo_webinar   has_custom_bg_image \" id=\"\" style=\"background-image: url(https:\/\/nextcloud.com\/c\/uploads\/2023\/12\/pexels-pixabay-256395-scaled.jpg);\">\r\n\t<div class=\"container\">\r\n\t\t<div class=\"row\">\r\n\t\t\t<div class=\"col-12\">\r\n\t\t\t\t<div class=\"text-block \">\r\n\t\t\t\t\t<h2>Les avantages de Nextcloud Enterprise<\/h2><p>Seul Nextcloud Enterprise offre aux institutions \u00e9ducatives la fiabilit\u00e9, la s\u00e9curit\u00e9 et la conformit\u00e9 dont elles ont besoin pour d\u00e9ployer en toute confiance des applications dans des environnements critiques.<\/p>\n<a class=\"c-btn btn-white\" href=\"https:\/\/nextcloud.com\/fr\/education\/\" target=\"_blank\">En savoir plus<\/a>\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/section>\r\n\n\n\n<h2 class=\"wp-block-heading\">Un logiciel puissant et \u00e9volutif pour les chercheurs<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les chercheurs universitaires et les doctorants travaillent avec une quantit\u00e9 importante de donn\u00e9es. Certaines donn\u00e9es sont faciles \u00e0 stocker, comme les fichiers et les documents, tandis que d&rsquo;autres, comme les images et les vid\u00e9os, les enregistrements sonores et les donn\u00e9es de mesure, n\u00e9cessitent une grande capacit\u00e9 de stockage. La plateforme Nextcloud peut g\u00e9rer de grandes quantit\u00e9s de donn\u00e9es, s&rsquo;adapte facilement et peut \u00eatre stock\u00e9e localement sur votre serveur.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Success stories dans le domaine de l&rsquo;\u00e9ducation<\/h2>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/nextcloud.com\/blog\/case_studies\/sorbonne-university-implements-nextcloud-solution\/\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/10\/Sorbonne_Uni-1024x576.png\" alt=\"Sorbonne University\" class=\"wp-image-146418 size-full\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2023\/10\/Sorbonne_Uni-1024x576.png 1024w, https:\/\/nextcloud.com\/c\/uploads\/2023\/10\/Sorbonne_Uni-300x169.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2023\/10\/Sorbonne_Uni-768x432.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2023\/10\/Sorbonne_Uni-1536x864.png 1536w, https:\/\/nextcloud.com\/c\/uploads\/2023\/10\/Sorbonne_Uni.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><strong>Sorbonne Universit\u00e9 \u00e0 Paris<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nextcloud a fourni \u00e0 l&rsquo;universit\u00e9 une solution cloud souveraine pour ses chercheurs, ses \u00e9tudiants et son personnel.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/nextcloud.com\/blog\/case_studies\/sorbonne-university-implements-nextcloud-solution\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lire l&rsquo;\u00e9tude de cas<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/nextcloud.com\/blog\/case_studies\/nextcloud-hub-improves-for-meiji-university\/\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/04\/nextcloud-case-study-meiji-university-1024x576.jpg\" alt=\"Nextcloud Hub improves convenience for Meiji University\" class=\"wp-image-110969 size-full\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2023\/04\/nextcloud-case-study-meiji-university-1024x576.jpg 1024w, https:\/\/nextcloud.com\/c\/uploads\/2023\/04\/nextcloud-case-study-meiji-university-300x169.jpg 300w, https:\/\/nextcloud.com\/c\/uploads\/2023\/04\/nextcloud-case-study-meiji-university-768x432.jpg 768w, https:\/\/nextcloud.com\/c\/uploads\/2023\/04\/nextcloud-case-study-meiji-university-1536x864.jpg 1536w, https:\/\/nextcloud.com\/c\/uploads\/2023\/04\/nextcloud-case-study-meiji-university.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><strong>Universit\u00e9 Meiji au Japon<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nextcloud Hub a consid\u00e9rablement am\u00e9lior\u00e9 la vie des \u00e9tudiants et des professeurs.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/nextcloud.com\/blog\/case_studies\/nextcloud-hub-improves-for-meiji-university\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lire l&rsquo;\u00e9tude de cas<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Redonnez le contr\u00f4le \u00e0 votre \u00e9cole ou universit\u00e9<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nextcloud offre aux \u00e9coles et aux universit\u00e9s un contr\u00f4le total sur leurs donn\u00e9es, leur infrastructure informatique et leur avenir gr\u00e2ce \u00e0 la solution Nextcloud Hub. Avec une facilit\u00e9 d&rsquo;utilisation pour les \u00e9tudiants, une collaboration transparente pour les \u00e9ducateurs et de meilleures performances pour les chercheurs, Nextcloud peut r\u00e9pondre aux besoins de tous les d\u00e9partements.<\/p>\n\n\n<section class=\"promo-section promo_webinar   has_custom_bg_image  full-width \" id=\"\" style=\"background-image: url(https:\/\/nextcloud.com\/c\/uploads\/2023\/12\/pexels-pixabay-256395-scaled.jpg);\">\r\n\t<div class=\"container\">\r\n\t\t<div class=\"row\">\r\n\t\t\t<div class=\"col-12\">\r\n\t\t\t\t<div class=\"text-block \">\r\n\t\t\t\t\t<h2>Nextcloud dans l&rsquo;\u00e9ducation<\/h2><p>Nextcloud est un pionnier dans l&rsquo;accompagnement des institutions \u00e9ducatives vers un futur souverain en mati\u00e8re de donn\u00e9es.<\/p>\n<a class=\"c-btn btn-white\" href=\"https:\/\/nextcloud.com\/fr\/education\/\" target=\"_blank\">En savoir plus<\/a>\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/section>\r\n","protected":false},"excerpt":{"rendered":"<p>Nextcloud est une solution s\u00e9curis\u00e9e pour les \u00e9coles, les universit\u00e9s et les instituts de recherche. En savoir plus sur les caract\u00e9ristiques et les b\u00e9n\u00e9fices que vous pouvez en tirer !<\/p>\n","protected":false},"author":9,"featured_media":187173,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"publish_to_discourse":"","publish_post_category":"","wpdc_auto_publish_overridden":"","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"","discourse_permalink":"","wpdc_publishing_response":"","wpdc_publishing_error":"","footnotes":""},"categories":[273,272,327,281],"tags":[],"class_list":["post-203296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-fr","category-communaute","category-education-fr","category-general-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gardez vos donn\u00e9es dans votre institution \u00e9ducative : Utiliser Nextcloud localement dans les \u00e9tablissements scolaires et universitaires - Nextcloud<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nextcloud.com\/fr\/blog\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gardez vos donn\u00e9es dans votre institution \u00e9ducative : Utiliser Nextcloud localement dans les \u00e9tablissements scolaires et universitaires - Nextcloud\" \/>\n<meta property=\"og:description\" content=\"Nextcloud est une solution s\u00e9curis\u00e9e pour les \u00e9coles, les universit\u00e9s et les instituts de recherche. En savoir plus sur les caract\u00e9ristiques et les b\u00e9n\u00e9fices que vous pouvez en tirer !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nextcloud.com\/fr\/blog\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\/\" \/>\n<meta property=\"og:site_name\" content=\"Nextcloud\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nextclouders\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-07T10:05:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T10:25:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nextcloud.com\/c\/uploads\/2023\/12\/Featured-Image-Template-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mikaela Schneider\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mikaela Schneider\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/blog\\\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/blog\\\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\\\/\"},\"author\":{\"name\":\"Mikaela Schneider\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/#\\\/schema\\\/person\\\/fc00a8687f2943f2fdd96de6b0ff723e\"},\"headline\":\"Gardez vos donn\u00e9es dans votre institution \u00e9ducative : Utiliser Nextcloud localement dans les \u00e9tablissements scolaires et universitaires\",\"datePublished\":\"2023-12-07T10:05:46+00:00\",\"dateModified\":\"2024-03-07T10:25:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/blog\\\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\\\/\"},\"wordCount\":661,\"publisher\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/blog\\\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nextcloud.com\\\/c\\\/uploads\\\/2023\\\/12\\\/Featured-Image-Template.png\",\"articleSection\":[\"Blog\",\"Communaut\u00e9\",\"\u00c9ducation\",\"G\u00e9n\u00e9ral\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/blog\\\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\\\/\",\"url\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/blog\\\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\\\/\",\"name\":\"Gardez vos donn\u00e9es dans votre institution \u00e9ducative : Utiliser Nextcloud localement dans les \u00e9tablissements scolaires et universitaires - Nextcloud\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/blog\\\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/blog\\\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nextcloud.com\\\/c\\\/uploads\\\/2023\\\/12\\\/Featured-Image-Template.png\",\"datePublished\":\"2023-12-07T10:05:46+00:00\",\"dateModified\":\"2024-03-07T10:25:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/blog\\\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nextcloud.com\\\/fr\\\/blog\\\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/blog\\\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nextcloud.com\\\/c\\\/uploads\\\/2023\\\/12\\\/Featured-Image-Template.png\",\"contentUrl\":\"https:\\\/\\\/nextcloud.com\\\/c\\\/uploads\\\/2023\\\/12\\\/Featured-Image-Template.png\",\"width\":1920,\"height\":1080,\"caption\":\"Education\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/blog\\\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gardez vos donn\u00e9es dans votre institution \u00e9ducative : Utiliser Nextcloud localement dans les \u00e9tablissements scolaires et universitaires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/\",\"name\":\"Nextcloud\",\"description\":\"Regain control over your data\",\"publisher\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/#organization\",\"name\":\"Nextcloud\",\"url\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nextcloud.com\\\/c\\\/uploads\\\/2022\\\/10\\\/nextcloud-logo-blue-transparent.svg\",\"contentUrl\":\"https:\\\/\\\/nextcloud.com\\\/c\\\/uploads\\\/2022\\\/10\\\/nextcloud-logo-blue-transparent.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Nextcloud\"},\"image\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nextclouders\\\/\",\"https:\\\/\\\/x.com\\\/nextclouders\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/10827569\\\/\",\"https:\\\/\\\/youtube.com\\\/nextcloud\",\"https:\\\/\\\/www.instagram.com\\\/nextclouders\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/fr\\\/#\\\/schema\\\/person\\\/fc00a8687f2943f2fdd96de6b0ff723e\",\"name\":\"Mikaela Schneider\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g\",\"caption\":\"Mikaela Schneider\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gardez vos donn\u00e9es dans votre institution \u00e9ducative : Utiliser Nextcloud localement dans les \u00e9tablissements scolaires et universitaires - Nextcloud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nextcloud.com\/fr\/blog\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\/","og_locale":"fr_FR","og_type":"article","og_title":"Gardez vos donn\u00e9es dans votre institution \u00e9ducative : Utiliser Nextcloud localement dans les \u00e9tablissements scolaires et universitaires - Nextcloud","og_description":"Nextcloud est une solution s\u00e9curis\u00e9e pour les \u00e9coles, les universit\u00e9s et les instituts de recherche. En savoir plus sur les caract\u00e9ristiques et les b\u00e9n\u00e9fices que vous pouvez en tirer !","og_url":"https:\/\/nextcloud.com\/fr\/blog\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\/","og_site_name":"Nextcloud","article_publisher":"https:\/\/www.facebook.com\/Nextclouders\/","article_published_time":"2023-12-07T10:05:46+00:00","article_modified_time":"2024-03-07T10:25:01+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/nextcloud.com\/c\/uploads\/2023\/12\/Featured-Image-Template-1024x576.png","type":"image\/png"}],"author":"Mikaela Schneider","twitter_misc":{"\u00c9crit par":"Mikaela Schneider","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nextcloud.com\/fr\/blog\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\/#article","isPartOf":{"@id":"https:\/\/nextcloud.com\/fr\/blog\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\/"},"author":{"name":"Mikaela Schneider","@id":"https:\/\/nextcloud.com\/fr\/#\/schema\/person\/fc00a8687f2943f2fdd96de6b0ff723e"},"headline":"Gardez vos donn\u00e9es dans votre institution \u00e9ducative : Utiliser Nextcloud localement dans les \u00e9tablissements scolaires et universitaires","datePublished":"2023-12-07T10:05:46+00:00","dateModified":"2024-03-07T10:25:01+00:00","mainEntityOfPage":{"@id":"https:\/\/nextcloud.com\/fr\/blog\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\/"},"wordCount":661,"publisher":{"@id":"https:\/\/nextcloud.com\/fr\/#organization"},"image":{"@id":"https:\/\/nextcloud.com\/fr\/blog\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\/#primaryimage"},"thumbnailUrl":"https:\/\/nextcloud.com\/c\/uploads\/2023\/12\/Featured-Image-Template.png","articleSection":["Blog","Communaut\u00e9","\u00c9ducation","G\u00e9n\u00e9ral"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/nextcloud.com\/fr\/blog\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\/","url":"https:\/\/nextcloud.com\/fr\/blog\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\/","name":"Gardez vos donn\u00e9es dans votre institution \u00e9ducative : Utiliser Nextcloud localement dans les \u00e9tablissements scolaires et universitaires - Nextcloud","isPartOf":{"@id":"https:\/\/nextcloud.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nextcloud.com\/fr\/blog\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\/#primaryimage"},"image":{"@id":"https:\/\/nextcloud.com\/fr\/blog\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\/#primaryimage"},"thumbnailUrl":"https:\/\/nextcloud.com\/c\/uploads\/2023\/12\/Featured-Image-Template.png","datePublished":"2023-12-07T10:05:46+00:00","dateModified":"2024-03-07T10:25:01+00:00","breadcrumb":{"@id":"https:\/\/nextcloud.com\/fr\/blog\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nextcloud.com\/fr\/blog\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nextcloud.com\/fr\/blog\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\/#primaryimage","url":"https:\/\/nextcloud.com\/c\/uploads\/2023\/12\/Featured-Image-Template.png","contentUrl":"https:\/\/nextcloud.com\/c\/uploads\/2023\/12\/Featured-Image-Template.png","width":1920,"height":1080,"caption":"Education"},{"@type":"BreadcrumbList","@id":"https:\/\/nextcloud.com\/fr\/blog\/gardez-vos-donnees-dans-votre-institution-educative-utiliser-nextcloud-localement-dans-les-etablissements-scolaires-et-universitaires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nextcloud.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Gardez vos donn\u00e9es dans votre institution \u00e9ducative : Utiliser Nextcloud localement dans les \u00e9tablissements scolaires et universitaires"}]},{"@type":"WebSite","@id":"https:\/\/nextcloud.com\/fr\/#website","url":"https:\/\/nextcloud.com\/fr\/","name":"Nextcloud","description":"Regain control over your data","publisher":{"@id":"https:\/\/nextcloud.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nextcloud.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nextcloud.com\/fr\/#organization","name":"Nextcloud","url":"https:\/\/nextcloud.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nextcloud.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","contentUrl":"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","width":"1024","height":"1024","caption":"Nextcloud"},"image":{"@id":"https:\/\/nextcloud.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Nextclouders\/","https:\/\/x.com\/nextclouders","https:\/\/www.linkedin.com\/company\/10827569\/","https:\/\/youtube.com\/nextcloud","https:\/\/www.instagram.com\/nextclouders\/"]},{"@type":"Person","@id":"https:\/\/nextcloud.com\/fr\/#\/schema\/person\/fc00a8687f2943f2fdd96de6b0ff723e","name":"Mikaela Schneider","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g","caption":"Mikaela Schneider"}}]}},"featured_media_url":"https:\/\/nextcloud.com\/c\/uploads\/2023\/12\/Featured-Image-Template.png","_links":{"self":[{"href":"https:\/\/nextcloud.com\/fr\/wp-json\/wp\/v2\/posts\/203296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nextcloud.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nextcloud.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/fr\/wp-json\/wp\/v2\/comments?post=203296"}],"version-history":[{"count":0,"href":"https:\/\/nextcloud.com\/fr\/wp-json\/wp\/v2\/posts\/203296\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/fr\/wp-json\/wp\/v2\/media\/187173"}],"wp:attachment":[{"href":"https:\/\/nextcloud.com\/fr\/wp-json\/wp\/v2\/media?parent=203296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nextcloud.com\/fr\/wp-json\/wp\/v2\/categories?post=203296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nextcloud.com\/fr\/wp-json\/wp\/v2\/tags?post=203296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}