{"id":327391,"date":"2025-08-07T07:00:00","date_gmt":"2025-08-07T05:00:00","guid":{"rendered":"https:\/\/nextcloud.com\/?post_type=press_releases&#038;p=327391"},"modified":"2025-08-07T11:39:05","modified_gmt":"2025-08-07T09:39:05","slug":"soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras","status":"publish","type":"press_releases","link":"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/","title":{"rendered":"Soberan\u00eda digital: Finlandia lidera por delante de Alemania y los Pa\u00edses Bajos \u2013 Espa\u00f1a por detras"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>El Reino Unido, Espa\u00f1a, Italia, Dinamarca, Noruega y B\u00e9lgica quedan rezagados en soberan\u00eda digital<\/li>\n\n\n\n<li>Existe una discrepancia entre la sociedad civil y la pol\u00edtica en el sector p\u00fablico de varios pa\u00edses<\/li>\n\n\n\n<li>Nextcloud publica el primer \u00cdndice de Soberan\u00eda Digital<\/li>\n<\/ul>\n\n<p>Finlandia (64,5) es el pa\u00eds con mayor adopci\u00f3n de infraestructura digital soberana, seguido de Alemania (53,85) y los Pa\u00edses Bajos (36,32). Por el contrario, el Reino Unido (9,21), B\u00e9lgica (7,15), Italia (6,5), Espa\u00f1a (7,01) y Dinamarca (6,5) se sit\u00faan por debajo de la media europea (16,31). Estos son los resultados del primer <a href=\"https:\/\/dsi.nextcloud.com\/\">\u00cdndice de Soberan\u00eda Digital<\/a> (DSI) publicado por la empresa de software de c\u00f3digo abierto Nextcloud, que mide el uso de tecnolog\u00edas autohospedadas en m\u00e1s que 50 pa\u00edses.  <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/08\/Nextcloud-Digital-Sovereignty-Index-1024x576.png\" alt=\"\" class=\"wp-image-327115\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/08\/Nextcloud-Digital-Sovereignty-Index-1024x576.png 1024w, https:\/\/nextcloud.com\/c\/uploads\/2025\/08\/Nextcloud-Digital-Sovereignty-Index-300x169.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2025\/08\/Nextcloud-Digital-Sovereignty-Index-768x432.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2025\/08\/Nextcloud-Digital-Sovereignty-Index-1536x864.png 1536w, https:\/\/nextcloud.com\/c\/uploads\/2025\/08\/Nextcloud-Digital-Sovereignty-Index.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p>El debate en torno a la soberan\u00eda digital ha cobrado impulso desde principios de a\u00f1o y abarca temas como la protecci\u00f3n de datos sensibles, la evitaci\u00f3n de la dependencia de un proveedor y la garant\u00eda del control democr\u00e1tico sobre la infraestructura. El \u00cdndice de Soberan\u00eda Digital (DSI) muestra el estado de dicha infraestructura y analiza m\u00e1s que 50 soluciones de software autohospedadas populares para el alojamiento de archivos, el trabajo en grupo, la comunicaci\u00f3n y la gesti\u00f3n de proyectos, y muestra el n\u00famero de implementaciones por cada 100.000 ciudadanos en relaci\u00f3n con otros pa\u00edses.  <\/p>\n\n<p>\u00abLa investigaci\u00f3n muestra un alto nivel de concienciaci\u00f3n en Alemania y los Pa\u00edses Bajos. Los particulares y las peque\u00f1as y medianas empresas utilizan tecnolog\u00edas autohospedadas, que a menudo son de c\u00f3digo abierto. Sin embargo, el sector p\u00fablico de ambos pa\u00edses sigue dependiendo en gran medida de las grandes empresas tecnol\u00f3gicas. Esta brecha indica que las organizaciones gubernamentales dependen profundamente de los grandes proveedores tecnol\u00f3gicos extranjeros, mientras que los ciudadanos y las peque\u00f1as empresas demuestran que se preocupan por la soberan\u00eda digital\u00bb, afirma Frank Karlitschek, director ejecutivo y fundador de Nextcloud.   <\/p>\n\n<p>\u00abLa administraci\u00f3n p\u00fablica depende en gran medida de los productos de los monopolios digitales y corre el riesgo de pagar precios exorbitantes con el dinero de los contribuyentes a largo plazo. El d\u00e9ficit de servicios de la UE en materia de licencias de software, servicios en la nube y otros costes con Estados Unidos alcanz\u00f3 el a\u00f1o pasado un nivel r\u00e9cord alarmante de 148 000 millones de euros\u00bb, afirm\u00f3 <strong> <\/strong>Harald Wehnes, profesor de inform\u00e1tica de W\u00fcrzburg\/Alemania.<\/p>\n\n<p><strong>El Reino Unido, Espa\u00f1a, Italia, Dinamarca, Noruega y B\u00e9lgica se quedan atr\u00e1s en soberan\u00eda digital<\/strong><\/p>\n\n<p>Aunque se sit\u00faan por encima de la media de la UE, Francia (25,1), Austria (20,23) y Suiza (23,32) est\u00e1n por detr\u00e1s de los l\u00edderes. La puntuaci\u00f3n total de Francia se ve favorecida por el elevado n\u00famero de herramientas de autoalojamiento e infraestructura, como Plex y Webmin, pero se queda rezagada en todas las dem\u00e1s aplicaciones y solo obtiene el octavo puesto en almacenamiento de datos y gesti\u00f3n de proyectos, e incluso el und\u00e9cimo en herramientas de comunicaci\u00f3n. <\/p>\n\n<p>Los pa\u00edses b\u00e1lticos, conocidos por sus avances en administraci\u00f3n electr\u00f3nica, se sit\u00faan sorprendentemente justo por encima de la media de la UE en soberan\u00eda digital: Letonia (16,63), Estonia (18,4) y Lituania (16,1).<\/p>\n\n<p>Noruega (6,35), B\u00e9lgica (7,15), Dinamarca (6,5), Espa\u00f1a (7,01) e Italia (6,49) obtienen puntuaciones significativamente inferiores a la media de la UE (16,31). Este ranking es especialmente interesante, ya que la soberan\u00eda digital ha sido un tema muy debatido en Dinamarca desde principios de a\u00f1o. <\/p>\n\n<p>\u00abCreo que Europa debe trabajar por la soberan\u00eda digital y mantener nuestros valores y normas de privacidad de datos. Las normas abiertas y las tecnolog\u00edas de c\u00f3digo abierto tambi\u00e9n son cada vez m\u00e1s importantes en este contexto y resultan esenciales para conseguir un panorama digital resistente\u00bb, ha declarado Pernille Tranberg, asesora independiente en \u00e9tica de los datos y la IA.<\/p>\n\n<p>\u00abEl objetivo de aumentar la soberan\u00eda tecnol\u00f3gica es reducir las dependencias y aumentar el control y la seguridad de los datos personales, as\u00ed como de los secretos comerciales de las empresas. Pero, sobre todo, necesitamos una soberan\u00eda tecnol\u00f3gica abierta, ya que solo con el c\u00f3digo abierto podemos permitir que los sectores p\u00fablico y privado creen e innoven de forma sostenible en Europa. Damos la bienvenida al \u00cdndice de Soberan\u00eda Digital, ya que muestra c\u00f3mo lo est\u00e1n haciendo los pa\u00edses europeos en este sentido\u00bb, declar\u00f3 Sebastian Raible, director de Relaciones con la UE de la Asociaci\u00f3n Empresarial Europea de C\u00f3digo Abierto APELL en Bruselas.  <\/p>\n\n<p>El Reino Unido (9,21), Canad\u00e1 (14,94) y Estados Unidos (14,88) tambi\u00e9n se sit\u00faan por debajo de la media de la UE (16,31).<\/p>\n\n<p>Los resultados completos est\u00e1n disponibles en el \u00cdndice de Soberan\u00eda Digital 2025: <a href=\"https:\/\/dsi.nextcloud.com\/\">dsi.nextcloud.com<\/a>.<\/p>\n\n<p><strong>Metodolog\u00eda 2025 \u00cdndice de Soberan\u00eda Digital (DSI)<\/strong><\/p>\n\n<p>Nextcloud investig\u00f3 el uso de unas 50 soluciones populares de software autoalojado para el alojamiento de archivos, la colaboraci\u00f3n, el trabajo en grupo, la comunicaci\u00f3n y la gesti\u00f3n de proyectos en m\u00e1s de 50 pa\u00edses el 28 de julio de 2025, con una presencia de m\u00e1s de 7,2 millones de servidores. La puntuaci\u00f3n del DSI utiliza una cifra entre 0 y 100 para mostrar el n\u00famero de implementaciones por cada 100 000 ciudadanos en relaci\u00f3n con otros pa\u00edses del \u00edndice. Cuanto mayor es la puntuaci\u00f3n, m\u00e1s visibles son los despliegues de infraestructura soberana. El DSI no es una medida absoluta de la soberan\u00eda, sino una indicaci\u00f3n s\u00f3lida de las decisiones que una sociedad toma respecto a sus datos. Es importante se\u00f1alar que el \u00edndice se basa en el n\u00famero de despliegues, no en su tama\u00f1o. Dado que las peque\u00f1as y medianas empresas, as\u00ed como los usuarios particulares que utilizan servidores, superan con creces a las grandes organizaciones, como los gobiernos o las grandes empresas, el \u00edndice refleja en mayor medida las elecciones de los individuos y las peque\u00f1as empresas que las de los gobiernos o las grandes corporaciones. Se trata de la primera vez que se realiza esta investigaci\u00f3n. Nextcloud no tiene acceso a los datos de sus clientes ni a los de otras soluciones de software de c\u00f3digo abierto utilizadas por terceros.      <\/p>\n\n<p><a><\/a><strong>Acerca de Nextcloud<\/strong><\/p>\n\n<p><a><\/a>Nextcloud Hub es la principal plataforma de colaboraci\u00f3n on premise y de c\u00f3digo abierto, con un enfoque s\u00f3lido en la protecci\u00f3n de datos. Es utilizada por decenas de miles de organizaciones para gestionar sus contenidos sensibles, garantizando el cumplimiento de normativas como el RGPD y la HIPAA. <\/p>\n\n<p><a><\/a>Nextcloud ofrece una plataforma unificada y completa que cubre todas las necesidades de colaboraci\u00f3n, permitiendo el intercambio de documentos, la edici\u00f3n en tiempo real, videoconferencias, gesti\u00f3n de calendarios, correos electr\u00f3nicos, entre otras funciones. Este enfoque integral, accesible desde interfaces m\u00f3viles, web y de escritorio, proporciona una experiencia de usuario excelente y aumenta la productividad.  <\/p>\n\n<p><a><\/a>Dise\u00f1ada con una arquitectura abierta y modular, Nextcloud permite a las organizaciones optimizar su colaboraci\u00f3n tanto interna como externa. Para m\u00e1s informaci\u00f3n, visite <a href=\"https:\/\/www.nextcloud.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">nextcloud.com\/es<\/a>. <\/p>\n\n<p><a><\/a><strong>Contacto de prensa<\/strong><br\/>Nextcloud GmbH<br\/>press@nextcloud.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finlandia (64,5) es el pa\u00eds con mayor adopci\u00f3n de infraestructura digital soberana, seguido de Alemania (53,85) y los Pa\u00edses Bajos (36,32). Por el contrario, el Reino Unido (9,21), B\u00e9lgica (7,15), Italia (6,5), Espa\u00f1a (7,01) y Dinamarca (6,5) se sit\u00faan por debajo de la media europea (16,31). Estos son los resultados del primer \u00cdndice de Soberan\u00eda [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":327119,"template":"","tags":[448,449],"class_list":["post-327391","press_releases","type-press_releases","status-publish","has-post-thumbnail","hentry","tag-digital-sovereignty","tag-study"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Soberan\u00eda digital: Finlandia lidera por delante de Alemania y los Pa\u00edses Bajos \u2013 Espa\u00f1a por detras - Nextcloud<\/title>\n<meta name=\"description\" content=\"\u00cdndice de Soberan\u00eda Digital: Finlandia a la cabeza, por delante de Alemania y Pa\u00edses Bajos. Reino Unido, Espa\u00f1a, Italia, Dinamarca, Noruega y B\u00e9lgica a la cola en soberan\u00eda digital.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soberan\u00eda digital: Finlandia lidera por delante de Alemania y los Pa\u00edses Bajos \u2013 Espa\u00f1a por detras - Nextcloud\" \/>\n<meta property=\"og:description\" content=\"\u00cdndice de Soberan\u00eda Digital: Finlandia a la cabeza, por delante de Alemania y Pa\u00edses Bajos. Reino Unido, Espa\u00f1a, Italia, Dinamarca, Noruega y B\u00e9lgica a la cola en soberan\u00eda digital.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/\" \/>\n<meta property=\"og:site_name\" content=\"Nextcloud\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nextclouders\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-07T09:39:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/08\/Nextcloud-Digital-Sovereignty-Index.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/\",\"url\":\"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/\",\"name\":\"Soberan\u00eda digital: Finlandia lidera por delante de Alemania y los Pa\u00edses Bajos \u2013 Espa\u00f1a por detras - Nextcloud\",\"isPartOf\":{\"@id\":\"https:\/\/nextcloud.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nextcloud.com\/c\/uploads\/2025\/08\/Nextcloud-Digital-Sovereignty-Index.png\",\"datePublished\":\"2025-08-07T05:00:00+00:00\",\"dateModified\":\"2025-08-07T09:39:05+00:00\",\"description\":\"\u00cdndice de Soberan\u00eda Digital: Finlandia a la cabeza, por delante de Alemania y Pa\u00edses Bajos. Reino Unido, Espa\u00f1a, Italia, Dinamarca, Noruega y B\u00e9lgica a la cola en soberan\u00eda digital.\",\"breadcrumb\":{\"@id\":\"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/#primaryimage\",\"url\":\"https:\/\/nextcloud.com\/c\/uploads\/2025\/08\/Nextcloud-Digital-Sovereignty-Index.png\",\"contentUrl\":\"https:\/\/nextcloud.com\/c\/uploads\/2025\/08\/Nextcloud-Digital-Sovereignty-Index.png\",\"width\":1920,\"height\":1080,\"caption\":\"Results of the first Digital Sovereignty Index (DSI) published by open source software company Nextcloud, measuring the use of self-hosted collaboration technologies across around 50 countries.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nextcloud.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soberan\u00eda digital: Finlandia lidera por delante de Alemania y los Pa\u00edses Bajos \u2013 Espa\u00f1a por detras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nextcloud.com\/es\/#website\",\"url\":\"https:\/\/nextcloud.com\/es\/\",\"name\":\"Nextcloud\",\"description\":\"Regain control over your data\",\"publisher\":{\"@id\":\"https:\/\/nextcloud.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nextcloud.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nextcloud.com\/es\/#organization\",\"name\":\"Nextcloud\",\"url\":\"https:\/\/nextcloud.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nextcloud.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg\",\"contentUrl\":\"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Nextcloud\"},\"image\":{\"@id\":\"https:\/\/nextcloud.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Nextclouders\/\",\"https:\/\/x.com\/nextclouders\",\"https:\/\/www.linkedin.com\/company\/10827569\/\",\"https:\/\/youtube.com\/nextcloud\",\"https:\/\/www.instagram.com\/nextclouders\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soberan\u00eda digital: Finlandia lidera por delante de Alemania y los Pa\u00edses Bajos \u2013 Espa\u00f1a por detras - Nextcloud","description":"\u00cdndice de Soberan\u00eda Digital: Finlandia a la cabeza, por delante de Alemania y Pa\u00edses Bajos. Reino Unido, Espa\u00f1a, Italia, Dinamarca, Noruega y B\u00e9lgica a la cola en soberan\u00eda digital.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/","og_locale":"es_ES","og_type":"article","og_title":"Soberan\u00eda digital: Finlandia lidera por delante de Alemania y los Pa\u00edses Bajos \u2013 Espa\u00f1a por detras - Nextcloud","og_description":"\u00cdndice de Soberan\u00eda Digital: Finlandia a la cabeza, por delante de Alemania y Pa\u00edses Bajos. Reino Unido, Espa\u00f1a, Italia, Dinamarca, Noruega y B\u00e9lgica a la cola en soberan\u00eda digital.","og_url":"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/","og_site_name":"Nextcloud","article_publisher":"https:\/\/www.facebook.com\/Nextclouders\/","article_modified_time":"2025-08-07T09:39:05+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/nextcloud.com\/c\/uploads\/2025\/08\/Nextcloud-Digital-Sovereignty-Index.png","type":"image\/png"}],"twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/","url":"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/","name":"Soberan\u00eda digital: Finlandia lidera por delante de Alemania y los Pa\u00edses Bajos \u2013 Espa\u00f1a por detras - Nextcloud","isPartOf":{"@id":"https:\/\/nextcloud.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/#primaryimage"},"image":{"@id":"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/#primaryimage"},"thumbnailUrl":"https:\/\/nextcloud.com\/c\/uploads\/2025\/08\/Nextcloud-Digital-Sovereignty-Index.png","datePublished":"2025-08-07T05:00:00+00:00","dateModified":"2025-08-07T09:39:05+00:00","description":"\u00cdndice de Soberan\u00eda Digital: Finlandia a la cabeza, por delante de Alemania y Pa\u00edses Bajos. Reino Unido, Espa\u00f1a, Italia, Dinamarca, Noruega y B\u00e9lgica a la cola en soberan\u00eda digital.","breadcrumb":{"@id":"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/#primaryimage","url":"https:\/\/nextcloud.com\/c\/uploads\/2025\/08\/Nextcloud-Digital-Sovereignty-Index.png","contentUrl":"https:\/\/nextcloud.com\/c\/uploads\/2025\/08\/Nextcloud-Digital-Sovereignty-Index.png","width":1920,"height":1080,"caption":"Results of the first Digital Sovereignty Index (DSI) published by open source software company Nextcloud, measuring the use of self-hosted collaboration technologies across around 50 countries."},{"@type":"BreadcrumbList","@id":"https:\/\/nextcloud.com\/es\/blog\/press_releases\/soberania-digital-finlandia-lidera-por-delante-de-alemania-y-los-paises-bajos-espana-por-detras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nextcloud.com\/es\/"},{"@type":"ListItem","position":2,"name":"Soberan\u00eda digital: Finlandia lidera por delante de Alemania y los Pa\u00edses Bajos \u2013 Espa\u00f1a por detras"}]},{"@type":"WebSite","@id":"https:\/\/nextcloud.com\/es\/#website","url":"https:\/\/nextcloud.com\/es\/","name":"Nextcloud","description":"Regain control over your data","publisher":{"@id":"https:\/\/nextcloud.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nextcloud.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nextcloud.com\/es\/#organization","name":"Nextcloud","url":"https:\/\/nextcloud.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nextcloud.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","contentUrl":"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","width":"1024","height":"1024","caption":"Nextcloud"},"image":{"@id":"https:\/\/nextcloud.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Nextclouders\/","https:\/\/x.com\/nextclouders","https:\/\/www.linkedin.com\/company\/10827569\/","https:\/\/youtube.com\/nextcloud","https:\/\/www.instagram.com\/nextclouders\/"]}]}},"_links":{"self":[{"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/press_releases\/327391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/press_releases"}],"about":[{"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/types\/press_releases"}],"author":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/users\/39"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/media\/327119"}],"wp:attachment":[{"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/media?parent=327391"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/tags?post=327391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}