{"id":22496,"date":"2022-06-17T06:41:56","date_gmt":"2022-06-17T06:41:56","guid":{"rendered":"https:\/\/nextcloud.com\/?p=22496"},"modified":"2023-07-05T21:25:52","modified_gmt":"2023-07-05T19:25:52","slug":"how-to-get-started-with-nextcloud","status":"publish","type":"post","link":"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/","title":{"rendered":"How to get started with Nextcloud"},"content":{"rendered":"\n<p>We are excited to invite you for a webinar about installing and configuring your own Nextcloud environment. Looking to get started with Nextcloud and need some guidance? This is the webinar you want to attend.<\/p>\n\n\n<section class=\"columns4-section\" id=\"Webinar\">\n\t<div class=\"container\">\n\t\t<div class=\"row\"><div class=\"col-12\"><div class=\"section-title\"><h6>How to get started with Nextcloud<\/h6><h2>How to get started with Nextcloud<\/h2><\/div><\/div><\/div><div class=\"row spacer align-items-center\"><div class=\"col-lg-6 order-lg-1\"><div class=\"image-slider\"><div><img decoding=\"async\" src=\"https:\/\/nextcloud.com\/c\/uploads\/webinar-how-to-get-started-with-nextcloud-featured-image.png\" alt=\"\"\/><\/div><\/div><\/div><div class=\"col-lg-6 order-lg-0\"><div class=\"text-block\"><div class=\"mobile-media\"><div class=\"image-slider\"><div><img decoding=\"async\" src=\"https:\/\/nextcloud.com\/c\/uploads\/webinar-how-to-get-started-with-nextcloud-featured-image.png\" alt=\"\"\/><\/div><\/div><\/div><p>Sign up for this free webinar on Thursday, 7 July 2022 to learn more on how to install Nextcloud Hub and configure for your end users. <\/p>\n<ul>\n<li>Date: Thursday, 7 July 2022<\/li>\n<li>Time: 3:00 PM (CEST)<\/li>\n<li>Duration: 60 minutes<\/li>\n<\/ul>\n<a class=\"c-btn btn-blue\" href=\"https:\/\/cloud.nextcloud.com\/apps\/forms\/yJ6adFwTg2asdF2e\" target=\"_blank\">Join this webinar<\/a><\/div><\/div><\/div>\t<\/div>\n<\/section>\n\n<section class=\"why-section\" id=\"\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-lg-6\">\n\t\t\t\t<div class=\"text-block\">\n\t\t\t\t\t<h2>In this webinar we cover<\/h2>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-lg-6\"><div class=\"text-block\"><ul>\n<li>The installation of your own Nextcloud instance.<\/li>\n<li>Some first and essential configuration steps.<\/li>\n<li>How to enable the use of apps within Nextcloud.<\/li>\n<li>How to prepare Nextcloud for your end users.<\/li>\n<\/ul>\n<\/div><\/div>\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section class=\"promo-section  \" id=\"join-webinar\" style=\"\" data-expiration=\"\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"text-block\">\n\t\t\t\t\t<p>Looking to get started with Nextcloud and need some guidance? <\/p>\n<p>This is the webinar you want to attend.<\/p>\n<a class=\"c-btn btn-white\" href=\"https:\/\/cloud.nextcloud.com\/apps\/forms\/yJ6adFwTg2asdF2e\" target=\"_blank\">Save my slot<\/a>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Join us for this free webinar on Thursday, 7 July 2022 to learn more on how to install and configure Nextcloud Hub for your end users. <\/p>\n","protected":false},"author":15,"featured_media":22684,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"publish_to_discourse":"","publish_post_category":"22","wpdc_auto_publish_overridden":"","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"377241","discourse_permalink":"https:\/\/help.nextcloud.com\/t\/how-to-get-started-with-nextcloud\/140740","wpdc_publishing_response":"success","wpdc_publishing_error":"","footnotes":""},"categories":[17,7,50],"tags":[],"class_list":["post-22496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business","category-news","category-webinar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How to get started with Nextcloud - Nextcloud<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How to get started with Nextcloud - Nextcloud\" \/>\n<meta property=\"og:description\" content=\"Join us for this free webinar on Thursday, 7 July 2022 to learn more on how to install and configure Nextcloud Hub for your end users.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/\" \/>\n<meta property=\"og:site_name\" content=\"Nextcloud\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nextclouders\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-17T06:41:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-05T19:25:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nextcloud.com\/wp-content\/uploads\/webinar-how-to-get-started-with-nextcloud-featured-image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"629\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Fabrice Mous\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabrice Mous\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/\"},\"author\":{\"name\":\"Fabrice Mous\",\"@id\":\"https:\/\/nextcloud.com\/es\/#\/schema\/person\/8f6650a713057e3f012a81f47863dd6c\"},\"headline\":\"How to get started with Nextcloud\",\"datePublished\":\"2022-06-17T06:41:56+00:00\",\"dateModified\":\"2023-07-05T19:25:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/\"},\"wordCount\":41,\"publisher\":{\"@id\":\"https:\/\/nextcloud.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nextcloud.com\/c\/uploads\/webinar-how-to-get-started-with-nextcloud-featured-image.png\",\"articleSection\":[\"Business\",\"News\",\"Webinar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/\",\"url\":\"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/\",\"name\":\"How to get started with Nextcloud - Nextcloud\",\"isPartOf\":{\"@id\":\"https:\/\/nextcloud.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nextcloud.com\/c\/uploads\/webinar-how-to-get-started-with-nextcloud-featured-image.png\",\"datePublished\":\"2022-06-17T06:41:56+00:00\",\"dateModified\":\"2023-07-05T19:25:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/#primaryimage\",\"url\":\"https:\/\/nextcloud.com\/c\/uploads\/webinar-how-to-get-started-with-nextcloud-featured-image.png\",\"contentUrl\":\"https:\/\/nextcloud.com\/c\/uploads\/webinar-how-to-get-started-with-nextcloud-featured-image.png\",\"width\":1200,\"height\":629},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nextcloud.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How to get started with Nextcloud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nextcloud.com\/es\/#website\",\"url\":\"https:\/\/nextcloud.com\/es\/\",\"name\":\"Nextcloud\",\"description\":\"Regain control over your data\",\"publisher\":{\"@id\":\"https:\/\/nextcloud.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nextcloud.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nextcloud.com\/es\/#organization\",\"name\":\"Nextcloud\",\"url\":\"https:\/\/nextcloud.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nextcloud.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg\",\"contentUrl\":\"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Nextcloud\"},\"image\":{\"@id\":\"https:\/\/nextcloud.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Nextclouders\/\",\"https:\/\/x.com\/nextclouders\",\"https:\/\/www.linkedin.com\/company\/10827569\/\",\"https:\/\/youtube.com\/nextcloud\",\"https:\/\/www.instagram.com\/nextclouders\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nextcloud.com\/es\/#\/schema\/person\/8f6650a713057e3f012a81f47863dd6c\",\"name\":\"Fabrice Mous\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nextcloud.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5841f47c282a7e515f59591ffd05005a9a0aa5a40e05b84643f9e0a600a63575?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5841f47c282a7e515f59591ffd05005a9a0aa5a40e05b84643f9e0a600a63575?s=96&d=mm&r=g\",\"caption\":\"Fabrice Mous\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"How to get started with Nextcloud - Nextcloud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/","og_locale":"es_ES","og_type":"article","og_title":"How to get started with Nextcloud - Nextcloud","og_description":"Join us for this free webinar on Thursday, 7 July 2022 to learn more on how to install and configure Nextcloud Hub for your end users.","og_url":"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/","og_site_name":"Nextcloud","article_publisher":"https:\/\/www.facebook.com\/Nextclouders\/","article_published_time":"2022-06-17T06:41:56+00:00","article_modified_time":"2023-07-05T19:25:52+00:00","og_image":[{"width":1200,"height":629,"url":"https:\/\/nextcloud.com\/wp-content\/uploads\/webinar-how-to-get-started-with-nextcloud-featured-image.png","type":"image\/png"}],"author":"Fabrice Mous","twitter_misc":{"Escrito por":"Fabrice Mous","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/#article","isPartOf":{"@id":"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/"},"author":{"name":"Fabrice Mous","@id":"https:\/\/nextcloud.com\/es\/#\/schema\/person\/8f6650a713057e3f012a81f47863dd6c"},"headline":"How to get started with Nextcloud","datePublished":"2022-06-17T06:41:56+00:00","dateModified":"2023-07-05T19:25:52+00:00","mainEntityOfPage":{"@id":"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/"},"wordCount":41,"publisher":{"@id":"https:\/\/nextcloud.com\/es\/#organization"},"image":{"@id":"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/#primaryimage"},"thumbnailUrl":"https:\/\/nextcloud.com\/c\/uploads\/webinar-how-to-get-started-with-nextcloud-featured-image.png","articleSection":["Business","News","Webinar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/","url":"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/","name":"How to get started with Nextcloud - Nextcloud","isPartOf":{"@id":"https:\/\/nextcloud.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/#primaryimage"},"image":{"@id":"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/#primaryimage"},"thumbnailUrl":"https:\/\/nextcloud.com\/c\/uploads\/webinar-how-to-get-started-with-nextcloud-featured-image.png","datePublished":"2022-06-17T06:41:56+00:00","dateModified":"2023-07-05T19:25:52+00:00","breadcrumb":{"@id":"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/#primaryimage","url":"https:\/\/nextcloud.com\/c\/uploads\/webinar-how-to-get-started-with-nextcloud-featured-image.png","contentUrl":"https:\/\/nextcloud.com\/c\/uploads\/webinar-how-to-get-started-with-nextcloud-featured-image.png","width":1200,"height":629},{"@type":"BreadcrumbList","@id":"https:\/\/nextcloud.com\/es\/blog\/how-to-get-started-with-nextcloud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nextcloud.com\/es\/"},{"@type":"ListItem","position":2,"name":"How to get started with Nextcloud"}]},{"@type":"WebSite","@id":"https:\/\/nextcloud.com\/es\/#website","url":"https:\/\/nextcloud.com\/es\/","name":"Nextcloud","description":"Regain control over your data","publisher":{"@id":"https:\/\/nextcloud.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nextcloud.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nextcloud.com\/es\/#organization","name":"Nextcloud","url":"https:\/\/nextcloud.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nextcloud.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","contentUrl":"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","width":"1024","height":"1024","caption":"Nextcloud"},"image":{"@id":"https:\/\/nextcloud.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Nextclouders\/","https:\/\/x.com\/nextclouders","https:\/\/www.linkedin.com\/company\/10827569\/","https:\/\/youtube.com\/nextcloud","https:\/\/www.instagram.com\/nextclouders\/"]},{"@type":"Person","@id":"https:\/\/nextcloud.com\/es\/#\/schema\/person\/8f6650a713057e3f012a81f47863dd6c","name":"Fabrice Mous","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nextcloud.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5841f47c282a7e515f59591ffd05005a9a0aa5a40e05b84643f9e0a600a63575?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5841f47c282a7e515f59591ffd05005a9a0aa5a40e05b84643f9e0a600a63575?s=96&d=mm&r=g","caption":"Fabrice Mous"}}]}},"featured_media_url":"https:\/\/nextcloud.com\/c\/uploads\/webinar-how-to-get-started-with-nextcloud-featured-image.png","_links":{"self":[{"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/posts\/22496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/comments?post=22496"}],"version-history":[{"count":0,"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/posts\/22496\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/media\/22684"}],"wp:attachment":[{"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/media?parent=22496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/categories?post=22496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/tags?post=22496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}