{"id":252333,"date":"2025-03-13T13:34:45","date_gmt":"2025-03-13T12:34:45","guid":{"rendered":"https:\/\/nextcloud.com\/?page_id=252333"},"modified":"2025-04-22T14:16:05","modified_gmt":"2025-04-22T12:16:05","slug":"digitalization","status":"publish","type":"page","link":"https:\/\/nextcloud.com\/es\/government\/digitalization\/","title":{"rendered":"Digitalization of the public sector"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=\u00bbgovernment titlebar\u00bb css=\u00bb.vc_custom_1661504975081{background-image: url(https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/08\/nextcloud-government-bg.jpg?id=53490) !important;}\u00bb][vc_row content_placement=\u00bbmiddle\u00bb][vc_column width=\u00bb3\/5&#8243;][vc_column_text css=\u00bb\u00bb el_class=\u00bbpage-title\u00bb]<\/p>\n<h1>Digitalization<br \/>\nof the public sector<\/h1>\n<p>[\/vc_column_text][vc_column_text css=\u00bb\u00bb el_class=\u00bbpage-subtitle notBold\u00bb]<\/p>\n<h4>Addressing digitalization of the public sector with an open source platform<\/h4>\n<p>[\/vc_column_text][\/vc_column][vc_column width=\u00bb2\/5&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_section el_class=\u00bbvertical-page-intro\u00bb css=\u00bb.vc_custom_1662133301793{background-image: url(https:\/\/nextcloud.com\/wp-content\/uploads\/2022\/08\/nextcloud-logo-icon-light-bg.svg?id=53508) !important;}\u00bb][vc_row gap=\u00bb10&#8243; content_placement=\u00bbmiddle\u00bb css=\u00bb.vc_custom_1661330748435{padding-right: 3rem !important;padding-left: 3rem !important;}\u00bb el_class=\u00bbwith_padding\u00bb][vc_column width=\u00bb1\/6&#8243;][\/vc_column][vc_column width=\u00bb2\/3&#8243;][vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: center;\">The public sector is expected to offer digital online services to citizens in a digitally sovereign and secure way. Nextcloud offers the first open source platform to address the unique challenges governments at all levels face.<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/6&#8243;][\/vc_column][\/vc_row][vc_row gap=\u00bb30&#8243; equal_height=\u00bbyes\u00bb el_class=\u00bbiconboxes\u00bb][vc_column width=\u00bb1\/3&#8243; el_class=\u00bbiconbox\u00bb][vc_icon icon_fontawesome=\u00bbfas fa-user-clock\u00bb color=\u00bbcustom\u00bb css=\u00bb\u00bb custom_color=\u00bb#0082c9&#8243;][vc_column_text css=\u00bb\u00bb el_class=\u00bbiconbox_title\u00bb]<\/p>\n<h4>Staff shortages &amp; limited resources<\/h4>\n<p>[\/vc_column_text][vc_column_text css=\u00bb\u00bb el_class=\u00bbsolution_box\u00bb]<span class=\"mainColor\" style=\"font-weight: bold;\">Solution: <\/span> Nextcloud integrates a broad range of collaboration abilities including Nextcloud Flow, an easy-to-use automation tool, designed to help organizations streamline tasks and improve productivity.[\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/3&#8243; el_class=\u00bbiconbox\u00bb][vc_icon icon_fontawesome=\u00bbfas fa-clipboard-check\u00bb color=\u00bbcustom\u00bb css=\u00bb\u00bb custom_color=\u00bb#0082c9&#8243;][vc_column_text css=\u00bb\u00bb el_class=\u00bbiconbox_title\u00bb]<\/p>\n<h4>Data security &amp; compliance<\/h4>\n<p>[\/vc_column_text][vc_column_text css=\u00bb\u00bb el_class=\u00bbsolution_box\u00bb]<span class=\"mainColor\" style=\"font-weight: bold;\">Solution: <\/span> Nextcloud offers full control over infrastructure and data, preventing vendor lock-in. With privacy and data sovereignty at its core, Nextcloud Flow is ideal for sectors requiring high levels of security, such as healthcare and public administration.[\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/3&#8243; el_class=\u00bbiconbox\u00bb][vc_icon icon_fontawesome=\u00bbfas fa-sync-alt\u00bb color=\u00bbcustom\u00bb css=\u00bb\u00bb custom_color=\u00bb#0082c9&#8243;][vc_column_text css=\u00bb\u00bb el_class=\u00bbiconbox_title\u00bb]<\/p>\n<h4>Process efficiency<\/h4>\n<p>[\/vc_column_text][vc_column_text css=\u00bb\u00bb el_class=\u00bbsolution_box\u00bb]<span class=\"mainColor\" style=\"font-weight: bold;\">Solution: <\/span> Nextcloud is optimized for sharing processes and knowledge across departments. With Flow it&#8217;s easy to automate routine and repetitive tasks, allowing teams to focus on high-value work.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section el_id=\u00bbquotes\u00bb css=\u00bb.vc_custom_1725535555526{padding-top: 0px !important;}\u00bb el_class=\u00bbnc_default_section\u00bb][vc_row][vc_column]                      <div class=\"single_quotes_carousel owl-carousel owl-theme\">\n                  \n                    <div class=\"nc_single_quote speaker imageCenter\">\n                    <div class=\"quote_image\">\n                        <img decoding=\"async\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2024\/06\/schleswig-holstein-nextcloud-collaboration-AI-development.jpg\" alt=\"Quote - Dirk Schr\u00f6dter\">\t\n                    <\/div>\n\n                    <div class=\"title_position\">\n                        <div class=\"quote_title\">\n                            <h4>\n                                Dirk Schr\u00f6dter                            <\/h4>\n                        <\/div>\n\n                                                <div class=\"position\">\n                            Head of the State Chancellery and Digitization Minister of the State of Schleswig-Holstein                         <\/div>\n                                            <\/div>\n\n                    <div class=\"quote\">\n                        Public administration in Germany is facing the huge challenge of offering citizens administrative services online. In the future, this will be facilitated by an open source automation tool for specialist procedures from an established provider such as Nextcloud. We look forward to contributing to the development of this groundbreaking tool and ensuring that its capabilities match the needs of the administration.                     <\/div>\n\n                    \n                    <\/div>\n\n            \n                    <div class=\"nc_single_quote speaker imageCenter\">\n                    <div class=\"quote_image\">\n                        <img decoding=\"async\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/richter-portrait-e1725534776769.jpg\" alt=\"Quote - Markus Richter\">\t\n                    <\/div>\n\n                    <div class=\"title_position\">\n                        <div class=\"quote_title\">\n                            <h4>\n                                Markus Richter                            <\/h4>\n                        <\/div>\n\n                                                <div class=\"position\">\n                            State Secretary at the Federal Ministry of the Interior and for Home Affairs and Federal Government Commissioner for Information Technology                        <\/div>\n                                            <\/div>\n\n                    <div class=\"quote\">\n                        The Online Access Act obliges the public sector to provide all administrative services digitally in future. Open source software should be given priority here. We are therefore delighted that the 'Open Collaboration Services' are the first 100% open source solution with which specialist procedures can be implemented quickly and easily. Open source enables the simple sharing of specialist procedures on Open CoDE, which saves costs and strengthens digital sovereignty.                    <\/div>\n\n                    \n                    <\/div>\n\n            \n                    <div class=\"nc_single_quote speaker imageCenter\">\n                    <div class=\"quote_image\">\n                        <img decoding=\"async\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/zendis-logo.svg\" alt=\"Quote - Leonhard Kugler\">\t\n                    <\/div>\n\n                    <div class=\"title_position\">\n                        <div class=\"quote_title\">\n                            <h4>\n                                Leonhard Kugler                            <\/h4>\n                        <\/div>\n\n                                                <div class=\"position\">\n                            Head of Open Source Platform at ZenDiS                        <\/div>\n                                            <\/div>\n\n                    <div class=\"quote\">\n                        Whether it\u2019s the consultation process for the OZG framework architecture or specialist applications based on no-code\/low-code principles: the latest use cases clearly demonstrate that Open CoDE is increasingly becoming the central platform for the sovereign digitalization of public administration in Germany. We are very pleased about this.                    <\/div>\n\n                    \n                    <\/div>\n\n                    \n      <\/div>\n      [\/vc_column][\/vc_row][\/vc_section][vc_section el_class=\u00bbnc_default_section lightBG lightBlueGradient\u00bb css=\u00bb.vc_custom_1725519310290{background-image: url(https:\/\/nextcloud.com\/c\/uploads\/2022\/08\/nextcloud-government-bg.jpg?id=53490) !important;}\u00bb][vc_row][vc_column width=\u00bb1\/2&#8243;][vc_column_text css=\u00bb\u00bb el_class=\u00bbnc_text_as_separator\u00bb]Key benefits[\/vc_column_text][vc_column_text css=\u00bb\u00bb el_class=\u00bbnc-section-title\u00bb]<\/p>\n<h2>Nextcloud for public adminstration<\/h2>\n<p>[\/vc_column_text][vc_column_text css=\u00bb\u00bb]Nextcloud&#8217;s collaboration solutions are used by tens of thousands of public administrations, including many EU institutions as well as federal, state and local administrations. It supports digitalization of the public sector in countries like France, the Netherlands, Serbia, Canada, Australia, Brazil, and the USA.[\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/2&#8243;][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1725519372531{margin-top: 2rem !important;margin-bottom: 2rem !important;}\u00bb][vc_column]      <div class=\"iconbox_repeater\" data-disable_carousel=\"\">\n          \t\t\t<div class=\"iconboxes sameHeightItemsCarousel notTruncated\">\n              \n\t\t\t\t\t\t<div id=\"\" class=\"iconboxes_carousel owl-carousel owl-theme\" data-items-desktop=\"4\">\n\t\t\t\n                                        <div class=\"nc_iconbox iconbox feature_iconbox \">\n\t\t\t\t\t  \t \n\t\t\t\t\t\t<div class=\"link_replacement no_scroll \">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"iconbox_container  no_link \">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<div class=\"top_title\">\n\t\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t\t\t<h4>Data security & privacy<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\t\t\t\tMaintain full control over your data with GDPR compliance and country-specific demands. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t \n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t                      <div class=\"nc_iconbox iconbox feature_iconbox \">\n\t\t\t\t\t  \t \n\t\t\t\t\t\t<div class=\"link_replacement no_scroll \">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"iconbox_container  no_link \">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<div class=\"top_title\">\n\t\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t\t\t<h4>Efficient collaboration<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\t\t\t\tSecure, remote collaboration on documents, projects, and video meetings.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t \n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t                      <div class=\"nc_iconbox iconbox feature_iconbox \">\n\t\t\t\t\t  \t \n\t\t\t\t\t\t<div class=\"link_replacement no_scroll \">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"iconbox_container  no_link \">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<div class=\"top_title\">\n\t\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t\t\t<h4>Scalable solution<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\t\t\t\tNextcloud adapts to the needs of any governmental unit, big or small.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t \n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t                      <div class=\"nc_iconbox iconbox feature_iconbox \">\n\t\t\t\t\t  \t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/nextcloud.com\/flow\/\" target=\"\" title=\"Automate processes with Nextcloud Flow\" >\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"iconbox_container \">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<div class=\"top_title\">\n\t\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t\t\t<h4>Automate processes with Nextcloud Flow<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\t\t\t\tStreamline administrative workflows and create online services without programming skills within a user friendly interface.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t                      <div class=\"nc_iconbox iconbox feature_iconbox \">\n\t\t\t\t\t  \t \n\t\t\t\t\t\t<div class=\"link_replacement no_scroll \">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"iconbox_container  no_link \">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<div class=\"top_title\">\n\t\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t\t\t<h4>\u201eOne for All\u201c-Principle<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\t\t\t\tOnce created, online services can be shared between agencies, municipalities, or public utilities via open repositories like github or country-specific platforms like Open CoDE in Germany or the Mission logiciels libres in France.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t \n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t                      <div class=\"nc_iconbox iconbox feature_iconbox \">\n\t\t\t\t\t  \t \n\t\t\t\t\t\t<div class=\"link_replacement no_scroll \">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"iconbox_container  no_link \">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<div class=\"top_title\">\n\t\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t\t\t<h4>Digital sovereignty<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\t\t\t\tAs a pure software vendor, Nextcloud does not force customers to host in its data centers but works with a variety of leading partners to provide SaaS or on premise solutions.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t \n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t              \t<\/div>\n\t\t\t  \t \n\n\t\t\t<\/div>\n        \n      <\/div>\n\t\t[\/vc_column][\/vc_row][vc_row el_class=\u00bbbtns-inline\u00bb][vc_column][vc_btn title=\u00bbGet a quote\u00bb i_icon_fontawesome=\u00bbfas fa-paper-plane\u00bb css=\u00bb.vc_custom_1674489206135{margin-right: 15px !important;}\u00bb add_icon=\u00bbtrue\u00bb el_class=\u00bbbtn-main\u00bb link=\u00bburl:%2Fget-a-quote%3Fsector%3Dgovernment\u00bb][vc_btn title=\u00bbMore about Flow\u00bb i_align=\u00bbright\u00bb i_icon_fontawesome=\u00bbfa fa-solid fa-angle-right\u00bb css=\u00bb.vc_custom_1745324001697{margin-right: 15px !important;}\u00bb add_icon=\u00bbtrue\u00bb el_class=\u00bbbtn-outline\u00bb link=\u00bburl:https%3A%2F%2Fnextcloud.com%2Fflow%2F|target:_blank\u00bb][\/vc_column][\/vc_row][\/vc_section][vc_section el_class=\u00bbnc_default_section\u00bb][vc_row css=\u00bb.vc_custom_1725533023907{margin-bottom: 3rem !important;}\u00bb][vc_column][vc_column_text css=\u00bb\u00bb el_class=\u00bbnc_text_as_separator\u00bb]<\/p>\n<p style=\"text-align: center;\">The solution for the Public Sector<\/p>\n<p>[\/vc_column_text][vc_column_text css=\u00bb\u00bb el_class=\u00bbnc-section-title\u00bb]<\/p>\n<h2 style=\"text-align: center;\">Our Open Source Platform for the digitalization<br \/>\nof processes and citizen facing services<\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row gap=\u00bb20&#8243; equal_height=\u00bbyes\u00bb el_class=\u00bbiconboxes\u00bb][vc_column width=\u00bb1\/2&#8243; offset=\u00bbvc_col-lg-4 vc_col-md-4&#8243;]<div class=\"nc_iconbox feature_iconbox wider_img \"><a href=\"https:\/\/nextcloud.com\/hub\/\" target=\"\" title=\"More about Hub\" class=\"\"><div class=\"iconbox_container \"><div class=\"icon\"><img decoding=\"async\" width=\"638\" height=\"576\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2024\/05\/hub8-content-collaboration-platform-hero-638x576.png\" class=\"attachment-large size-large\" alt=\"Nextcloud Hub online collaboration\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2024\/05\/hub8-content-collaboration-platform-hero-638x576.png 638w, https:\/\/nextcloud.com\/c\/uploads\/2024\/05\/hub8-content-collaboration-platform-hero-300x271.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2024\/05\/hub8-content-collaboration-platform-hero-768x693.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2024\/05\/hub8-content-collaboration-platform-hero.png 1200w\" sizes=\"(max-width: 638px) 100vw, 638px\" \/><\/div>\n\t<div class=\"title_and_description\"><h4 class=\"title\">Nextcloud Hub<\/h4><div class=\"description\">Nextcloud Hub is the leading open source, on-premises content collaboration platform with a strong focus on data protection. It is deployed by tens of thousands of organizations to stay in control of their sensitive content in compliance with privacy regulations like GDPR and HIPAA.<br \/>\nNextcloud Hub offers a modern, easy to use content collaboration platform accessible trough mobile, desktop and web interfaces.<\/div><span class=\"see_more\">More about Hub <svg id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" viewBox=\"0 0 24 24\"><path class=\"st0\" d=\"M12.6,12l-4.6-4.6,1.4-1.4,6,6-6,6-1.4-1.4,4.6-4.6Z\"\/><\/svg><\/span><\/div><\/div><\/a><\/div>[\/vc_column][vc_column width=\u00bb1\/2&#8243; offset=\u00bbvc_col-lg-4 vc_col-md-4&#8243;]<div class=\"nc_iconbox feature_iconbox wider_img \"><a href=\"https:\/\/www.open-collaboration-services.org\/\" target=\"_blank\" title=\"More about platform\" class=\"\"><div class=\"iconbox_container \"><div class=\"icon\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/nextcloud-hub-connected-apps-graphic.svg\" class=\"attachment-large size-large\" alt=\"\" \/><\/div>\n\t<div class=\"title_and_description\"><h4 class=\"title\">Nextcloud platform<\/h4><div class=\"description\">The Open Collaboration Services (OCS) API is designed to make it easy to connect your apps to any Content Collaboration Platform like Nextcloud. Built upon its open standards, over 400 apps already connect with Nextcloud Hub. The easy interoperability with a wide range of third party technologies has positioned it as a key solution for the digitalization for the public sector.<\/div><span class=\"see_more\">More about platform <svg id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" viewBox=\"0 0 24 24\"><path class=\"st0\" d=\"M12.6,12l-4.6-4.6,1.4-1.4,6,6-6,6-1.4-1.4,4.6-4.6Z\"\/><\/svg><\/span><\/div><\/div><\/a><\/div>[\/vc_column][vc_column width=\u00bb1\/2&#8243; offset=\u00bbvc_col-lg-4 vc_col-md-4&#8243;]<div class=\"nc_iconbox feature_iconbox wider_img \"><a href=\"https:\/\/nextcloud.com\/flow\/\" target=\"\" title=\"More about Flow\" class=\"\"><div class=\"iconbox_container \"><div class=\"icon\"><img decoding=\"async\" width=\"964\" height=\"576\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/nextcloud-flow-graphic-964x576.png\" class=\"attachment-large size-large\" alt=\"nextcloud-flow-graphic\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/nextcloud-flow-graphic-964x576.png 964w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/nextcloud-flow-graphic-300x179.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/nextcloud-flow-graphic-768x459.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/nextcloud-flow-graphic.png 1200w\" sizes=\"(max-width: 964px) 100vw, 964px\" \/><\/div>\n\t<div class=\"title_and_description\"><h4 class=\"title\">Nextcloud Flow<\/h4><div class=\"description\">With Nextcloud Flow, the digitalization of the public sector and administrative processes will be easier, more efficient and secure. Flow offers a graphical automation tool integrating various Nextcloud Hub components and data with external data processing systems, able to input, process and output data in a variety of ways.<br \/>\nNextcloud Flow is designed to help organizations improve their services, bringing processes online.<\/div><span class=\"see_more\">More about Flow <svg id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" viewBox=\"0 0 24 24\"><path class=\"st0\" d=\"M12.6,12l-4.6-4.6,1.4-1.4,6,6-6,6-1.4-1.4,4.6-4.6Z\"\/><\/svg><\/span><\/div><\/div><\/a><\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section el_class=\u00bbnc_default_section lightBG\u00bb css=\u00bb.vc_custom_1726050773306{margin-bottom: 0px !important;}\u00bb][vc_row][vc_column width=\u00bb1\/2&#8243;][vc_column_text css=\u00bb\u00bb el_class=\u00bbnc_text_as_separator\u00bb]Digitalisation of the Public Sector[\/vc_column_text][vc_column_text css=\u00bb\u00bb el_class=\u00bbnc-section-title\u00bb]<\/p>\n<h2>Why open source is the solution<\/h2>\n<p>[\/vc_column_text][vc_column_text css=\u00bb\u00bb]While the digital transformation of the public sector presents considerable challenges, open-source technology offers a robust and flexible path forward. By leveraging open-source cloud solutions, governments can address the unique pressures they face, from limited resources to the need for high security, all while paving the way for a more efficient, transparent, and responsive public sector.<\/p>\n<p>Given these challenges, open-source technology emerges as a compelling solution for the public sector\u2019s digital transformation.[\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/2&#8243;][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1726044965427{margin-top: 3rem !important;margin-bottom: 2rem !important;}\u00bb][vc_column]      <div class=\"iconbox_repeater\" data-disable_carousel=\"\">\n          \t\t\t<div class=\"iconboxes sameHeightItemsCarousel\">\n              \n\t\t\t\t\t\t<div id=\"\" class=\"iconboxes_carousel owl-carousel owl-theme\" data-items-desktop=\"3\">\n\t\t\t\n                                        <div class=\"nc_iconbox iconbox feature_iconbox \">\n\t\t\t\t\t  \t \n\t\t\t\t\t\t<div class=\"link_replacement no_scroll \">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"iconbox_container  no_link \">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t\t\t\t\t<i class=\"fas fa-check-circle\"><\/i>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<div class=\"top_title\">\n\t\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t\t\t<h4>Open-source software offers unparalleled flexibility<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\t\t\t\tThe collaborative nature of open-source development means that public administrations can benefit from each others innovations and improvements.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t \n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t                      <div class=\"nc_iconbox iconbox feature_iconbox \">\n\t\t\t\t\t  \t \n\t\t\t\t\t\t<div class=\"link_replacement no_scroll \">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"iconbox_container  no_link \">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t\t\t\t\t<i class=\"fas fa-check-circle\"><\/i>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<div class=\"top_title\">\n\t\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t\t\t<h4>Data security and sovereignty<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\t\t\t\tIn terms of data security and sovereignty, open-source provides a level of transparency that is hard to achieve with closed-source software. It can be scrutinized by security experts, reducing the risk of vulnerabilities and ensuring that the software adheres to the highest security standards. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t \n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t                      <div class=\"nc_iconbox iconbox feature_iconbox \">\n\t\t\t\t\t  \t \n\t\t\t\t\t\t<div class=\"link_replacement no_scroll \">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"iconbox_container  no_link \">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t\t\t\t\t<i class=\"fas fa-check-circle\"><\/i>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<div class=\"top_title\">\n\t\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t\t\t<h4>Control over data<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\t\t\t\tOpen-source solutions give governments complete control over their data, which is vital for maintaining compliance with national regulations and protecting citizen privacy.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t \n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t                      <div class=\"nc_iconbox iconbox feature_iconbox \">\n\t\t\t\t\t  \t \n\t\t\t\t\t\t<div class=\"link_replacement no_scroll \">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"iconbox_container  no_link \">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t\t\t\t\t<i class=\"fas fa-check-circle\"><\/i>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<div class=\"top_title\">\n\t\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t\t\t<h4>Scalability and interoperability<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\t\t\t\tThe scalability and interoperability of open-source systems make them ideal for public administrations that need to integrate various legacy systems or scale their services rapidly. As demands on public services continue to grow, the ability to scale efficiently and without exorbitant costs becomes increasingly important.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t \n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t                      <div class=\"nc_iconbox iconbox feature_iconbox \">\n\t\t\t\t\t  \t \n\t\t\t\t\t\t<div class=\"link_replacement no_scroll \">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"iconbox_container  no_link \">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t\t\t\t\t<i class=\"fas fa-check-circle\"><\/i>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<div class=\"top_title\">\n\t\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t\t\t<h4>Reduce redundancy<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\t\t\t\tThe inherent focus and architecture for sharing of most open source solutions is a powerful force to reduce redundancy and improve the re-use of solutions across the public sector. This standardizes and speeds up deployment and offers a large opportunity to significantly reduce costs.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t \n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t              \t<\/div>\n\t\t\t  \t \n\n\t\t\t<\/div>\n        \n      <\/div>\n\t\t[\/vc_column][\/vc_row][\/vc_section][vc_section el_id=\u00bbcta-contact\u00bb el_class=\u00bbcta-contact white-text cta_with_background\u00bb css=\u00bb.vc_custom_1725517606824{padding-top: 3rem !important;padding-bottom: 3rem !important;background-image: url(https:\/\/nextcloud.com\/c\/uploads\/2022\/08\/nextcloud-government-bg.jpg?id=53490) !important;}\u00bb][vc_row content_placement=\u00bbmiddle\u00bb][vc_column width=\u00bb1\/2&#8243; el_class=\u00bbtext-right\u00bb][vc_column_text el_class=\u00bbnc-section-title\u00bb]<\/p>\n<h2>Contact us now<\/h2>\n<p>[\/vc_column_text][vc_column_text css=\u00bb.vc_custom_1707209209064{margin-bottom: 0px !important;}\u00bb]Reduce risk, improve citizen communication and reduce<br \/>\noperational expenses with the leading content collaboration platform.<br \/>\nContact us now to learn how Nextcloud can help you![\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/2&#8243; el_class=\u00bbcta_buttons\u00bb][vc_btn title=\u00bbGet a quote\u00bb align=\u00bbleft\u00bb i_icon_fontawesome=\u00bbfas fa-paper-plane\u00bb add_icon=\u00bbtrue\u00bb el_class=\u00bbbtn-white\u00bb link=\u00bburl:%2Fget-a-quote%3Fsector%3Dgovernment\u00bb][vc_btn title=\u00bbTalk to us\u00bb align=\u00bbleft\u00bb i_icon_fontawesome=\u00bbfas fa-phone-alt\u00bb css=\u00bb.vc_custom_1707209237921{margin-bottom: 0px !important;}\u00bb add_icon=\u00bbtrue\u00bb el_class=\u00bbbtn-white-outline\u00bb link=\u00bburl:tel%3A%20%2B49%20711%2025%2024%2028%2090&#8243;][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>The public sector is expected to offer digital online services to citizens in a digitally sovereign and secure way. Nextcloud offers the first open source platform to address the unique challenges governments at all levels face.<\/p>\n","protected":false},"author":26,"featured_media":301728,"parent":11785,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"publish_to_discourse":"","publish_post_category":"","wpdc_auto_publish_overridden":"","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"","discourse_permalink":"","wpdc_publishing_response":"","wpdc_publishing_error":"","footnotes":""},"tags":[],"class_list":["post-252333","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Digitalization of the public sector - Nextcloud<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nextcloud.com\/es\/government\/digitalization\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digitalization of the public sector - Nextcloud\" \/>\n<meta property=\"og:description\" content=\"The public sector is expected to offer digital online services to citizens in a digitally sovereign and secure way. Nextcloud offers the first open source platform to address the unique challenges governments at all levels face.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nextcloud.com\/es\/government\/digitalization\/\" \/>\n<meta property=\"og:site_name\" content=\"Nextcloud\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nextclouders\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-22T12:16:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/04\/Nextcloud-Digitalization-of-the-public-sector.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nextcloud.com\/es\/government\/digitalization\/\",\"url\":\"https:\/\/nextcloud.com\/es\/government\/digitalization\/\",\"name\":\"Digitalization of the public sector - Nextcloud\",\"isPartOf\":{\"@id\":\"https:\/\/nextcloud.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nextcloud.com\/es\/government\/digitalization\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nextcloud.com\/es\/government\/digitalization\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nextcloud.com\/c\/uploads\/2025\/04\/Nextcloud-Digitalization-of-the-public-sector.png\",\"datePublished\":\"2025-03-13T12:34:45+00:00\",\"dateModified\":\"2025-04-22T12:16:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nextcloud.com\/es\/government\/digitalization\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nextcloud.com\/es\/government\/digitalization\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nextcloud.com\/es\/government\/digitalization\/#primaryimage\",\"url\":\"https:\/\/nextcloud.com\/c\/uploads\/2025\/04\/Nextcloud-Digitalization-of-the-public-sector.png\",\"contentUrl\":\"https:\/\/nextcloud.com\/c\/uploads\/2025\/04\/Nextcloud-Digitalization-of-the-public-sector.png\",\"width\":1920,\"height\":1080,\"caption\":\"Nextcloud - Digitalization of the public sector\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nextcloud.com\/es\/government\/digitalization\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nextcloud.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Government\",\"item\":\"https:\/\/nextcloud.com\/es\/government\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Digitalization of the public sector\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nextcloud.com\/es\/#website\",\"url\":\"https:\/\/nextcloud.com\/es\/\",\"name\":\"Nextcloud\",\"description\":\"Regain control over your data\",\"publisher\":{\"@id\":\"https:\/\/nextcloud.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nextcloud.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nextcloud.com\/es\/#organization\",\"name\":\"Nextcloud\",\"url\":\"https:\/\/nextcloud.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nextcloud.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg\",\"contentUrl\":\"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Nextcloud\"},\"image\":{\"@id\":\"https:\/\/nextcloud.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Nextclouders\/\",\"https:\/\/x.com\/nextclouders\",\"https:\/\/www.linkedin.com\/company\/10827569\/\",\"https:\/\/youtube.com\/nextcloud\",\"https:\/\/www.instagram.com\/nextclouders\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Digitalization of the public sector - Nextcloud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nextcloud.com\/es\/government\/digitalization\/","og_locale":"es_ES","og_type":"article","og_title":"Digitalization of the public sector - Nextcloud","og_description":"The public sector is expected to offer digital online services to citizens in a digitally sovereign and secure way. Nextcloud offers the first open source platform to address the unique challenges governments at all levels face.","og_url":"https:\/\/nextcloud.com\/es\/government\/digitalization\/","og_site_name":"Nextcloud","article_publisher":"https:\/\/www.facebook.com\/Nextclouders\/","article_modified_time":"2025-04-22T12:16:05+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/nextcloud.com\/c\/uploads\/2025\/04\/Nextcloud-Digitalization-of-the-public-sector.png","type":"image\/png"}],"twitter_misc":{"Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nextcloud.com\/es\/government\/digitalization\/","url":"https:\/\/nextcloud.com\/es\/government\/digitalization\/","name":"Digitalization of the public sector - Nextcloud","isPartOf":{"@id":"https:\/\/nextcloud.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nextcloud.com\/es\/government\/digitalization\/#primaryimage"},"image":{"@id":"https:\/\/nextcloud.com\/es\/government\/digitalization\/#primaryimage"},"thumbnailUrl":"https:\/\/nextcloud.com\/c\/uploads\/2025\/04\/Nextcloud-Digitalization-of-the-public-sector.png","datePublished":"2025-03-13T12:34:45+00:00","dateModified":"2025-04-22T12:16:05+00:00","breadcrumb":{"@id":"https:\/\/nextcloud.com\/es\/government\/digitalization\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nextcloud.com\/es\/government\/digitalization\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nextcloud.com\/es\/government\/digitalization\/#primaryimage","url":"https:\/\/nextcloud.com\/c\/uploads\/2025\/04\/Nextcloud-Digitalization-of-the-public-sector.png","contentUrl":"https:\/\/nextcloud.com\/c\/uploads\/2025\/04\/Nextcloud-Digitalization-of-the-public-sector.png","width":1920,"height":1080,"caption":"Nextcloud - Digitalization of the public sector"},{"@type":"BreadcrumbList","@id":"https:\/\/nextcloud.com\/es\/government\/digitalization\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nextcloud.com\/es\/"},{"@type":"ListItem","position":2,"name":"Government","item":"https:\/\/nextcloud.com\/es\/government\/"},{"@type":"ListItem","position":3,"name":"Digitalization of the public sector"}]},{"@type":"WebSite","@id":"https:\/\/nextcloud.com\/es\/#website","url":"https:\/\/nextcloud.com\/es\/","name":"Nextcloud","description":"Regain control over your data","publisher":{"@id":"https:\/\/nextcloud.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nextcloud.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nextcloud.com\/es\/#organization","name":"Nextcloud","url":"https:\/\/nextcloud.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nextcloud.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","contentUrl":"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","width":"1024","height":"1024","caption":"Nextcloud"},"image":{"@id":"https:\/\/nextcloud.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Nextclouders\/","https:\/\/x.com\/nextclouders","https:\/\/www.linkedin.com\/company\/10827569\/","https:\/\/youtube.com\/nextcloud","https:\/\/www.instagram.com\/nextclouders\/"]}]}},"_links":{"self":[{"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/pages\/252333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/comments?post=252333"}],"version-history":[{"count":93,"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/pages\/252333\/revisions"}],"predecessor-version":[{"id":305585,"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/pages\/252333\/revisions\/305585"}],"up":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/pages\/11785"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/media\/301728"}],"wp:attachment":[{"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/media?parent=252333"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nextcloud.com\/es\/wp-json\/wp\/v2\/tags?post=252333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}