{"id":93259,"date":"2023-02-02T10:55:38","date_gmt":"2023-02-02T09:55:38","guid":{"rendered":"https:\/\/nextcloud.com\/blog\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\/"},"modified":"2023-02-02T17:51:19","modified_gmt":"2023-02-02T16:51:19","slug":"600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen","status":"publish","type":"post","link":"https:\/\/nextcloud.com\/de\/blog\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\/","title":{"rendered":"600 Mitarbeiter der Berliner NGO AWO arbeiten \u00fcber Nextcloud zusammen"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Bei der AWO Berlin-Mitte arbeiten 600 Teammitglieder mit Nextcloud Hub und nutzen Files, Talk, Deck, Tasks und mehr, um zu kommunizieren, zu teilen, zu planen und mit oft sehr kritischen, pers\u00f6nlichen Daten zusammenzuarbeiten. Lesen Sie weiter und erfahren Sie, warum sich die AWO f\u00fcr Nextcloud entschieden hat.<\/p>\n\n<figure class=\"wp-block-image size-full is-style-default\"><img decoding=\"async\" width=\"1800\" height=\"650\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/uber_uns_startseite.png\" alt=\"Eine Reihe wei&#xDF;er Fahnen mit dem Logo der AWO Berlin-Mitte weht im Wind, dahinter ein gr&#xFC;nes Geb&#xFC;sch.\" class=\"wp-image-93008\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2023\/02\/uber_uns_startseite.png 1800w, https:\/\/nextcloud.com\/c\/uploads\/2023\/02\/uber_uns_startseite-300x108.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2023\/02\/uber_uns_startseite-1024x370.png 1024w, https:\/\/nextcloud.com\/c\/uploads\/2023\/02\/uber_uns_startseite-768x277.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2023\/02\/uber_uns_startseite-1536x555.png 1536w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Die <a href=\"https:\/\/awo-mitte.de\/\">AWO Berlin-Mitte<\/a> ist ein gro\u00dfer Anbieter von Sozialarbeit und Wohlfahrtspflege in Berlin. Sie ist eine Freiwilligen- und Mitgliederorganisation mit 1.300 Mitgliedern und bietet Dienstleistungen an, die von der Leitung von Kindertagesst\u00e4tten \u00fcber die Hilfe f\u00fcr Menschen mit Behinderungen und Obdachlose bis hin zu Dienstleistungen f\u00fcr asylsuchende Fl\u00fcchtlinge, Wohnungs- und Beratungsdienste und mehr reichen.<\/p>\n\n<p class=\"wp-block-paragraph\">Infolge der Pandemie wurde ein gro\u00dfer Teil der Beratungs- und Verwaltungsarbeit der Organisation auf Fernarbeit umgestellt. Um ihren Mitarbeitern und Freiwilligen die M\u00f6glichkeit zu geben, flexibel von zu Hause aus zu arbeiten, brauchten sie eine L\u00f6sung. Dar\u00fcber hinaus legte die AWO Berlin-Mitte gro\u00dfen Wert darauf, dass die neue L\u00f6sung im Gegensatz zu anderen g\u00e4ngigen Plattformen wie Microsoft und Google zu 100 % GDPR-konform ist. Aus diesem Grund wandte sich der angesehene Verband f\u00fcr Sozialarbeit an Nextcloud.<\/p>\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>&#8222;Nextcloud hat uns das Arbeiten unter den Bedingungen von Covid 19 erm\u00f6glicht.&#8220;<\/p><cite>&#8211; Peter Reif, IT und Datenmanagement bei AWO Berlin-Mitte<\/cite><\/blockquote><\/figure>\n\n<p class=\"wp-block-paragraph\">Nextcloud bietet der AWO Berlin-Mitte eine sichere Online-Zusammenarbeitsplattform, die ihren Bed\u00fcrfnissen entspricht. F\u00fcr die t\u00e4gliche Kommunikation und Zusammenarbeit mit Kollegen nutzen die Mitarbeiter Nextcloud Talk, Deck, Tasks und Polls. Zugriffskontrolllisten sind ein Schl\u00fcsselmerkmal f\u00fcr die Sicherheit und die Erf\u00fcllung der GDPR-Anforderungen machen Nextcloud zur idealen L\u00f6sung.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>GDPR-konforme L\u00f6sung<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Jeden Tag arbeiten die Mitarbeiter von Berlin-Mitte von Fall zu Fall mit den personenbezogenen Daten von Menschen. Die Sozialarbeiter tragen die Verantwortung daf\u00fcr, dass diese vertraulichen Daten nicht nach au\u00dfen dringen. Mit Nextcloud k\u00f6nnen die Mitarbeiter personenbezogene Daten verarbeiten, speichern und l\u00f6schen, ohne sich um den Datenschutz sorgen zu m\u00fcssen, da die Daten auf Servern liegen, die zu 100 % von der AWO kontrolliert werden. <\/p>\n\n<p class=\"wp-block-paragraph\">Die Erf\u00fcllung der europ\u00e4ischen und deutschen Datenschutzanforderungen war f\u00fcr die AWO Berlin-Mitte ein entscheidender Faktor bei der Entscheidungsfindung. Nextcloud bietet der AWO Berlin-Mitte eine sichere Online-Zusammenarbeitsplattform, die ihren Bed\u00fcrfnissen entspricht.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Unendliche Zusammenarbeit<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Derzeit wird Nextcloud von rund 600 Mitarbeitern der AWO Berlin aktiv genutzt. <\/p>\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>&#8222;Die Nutzer begr\u00fc\u00dfen und genie\u00dfen die kollaborative Natur von Nextcloud. Mit Talk k\u00f6nnen sie einzeln oder in Teams kommunizieren sowie Dokumente, Tabellen und Pr\u00e4sentationen teilen. Mit Deck k\u00f6nnen sie Aufgaben individuell oder in Zusammenarbeit in Teams organisieren und priorisieren.&#8220; <\/p><cite>&#8211; AWO Berlin-Mitte<\/cite><\/blockquote><\/figure>\n\n<p class=\"wp-block-paragraph\">Mit einer breiten Palette von Integrationen und Anwendungen, darunter Mindmap, Aufgaben und Umfragen, ist Nextcloud zu einem unverzichtbaren Tool f\u00fcr die Optimierung der Zusammenarbeit geworden.<\/p>\n\n<p class=\"wp-block-paragraph\">F\u00fcr die Zukunft plant die AWO Berlin, auch ihre Ehrenamtlichen in Nextcloud einzubinden &#8211; so k\u00f6nnen alle Mitglieder der Organisation zusammenarbeiten!<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Schl\u00fcsselfunktion f\u00fcr die AWO: ACLs<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">F\u00fcr Berlin-Mitte war das Vorhandensein konfigurierbarer Gruppenordner, die spezielle Zugriffs- und Autorisierungsrechte erm\u00f6glichen, ein Schl\u00fcssel zum Erfolg. Dies war besonders wichtig beim Umgang mit vertraulichen Daten in komplexen Diensten.<\/p>\n\n<p class=\"wp-block-paragraph\">Jetzt haben Administratoren die Kontrolle dar\u00fcber, was ihr Team innerhalb eines Ordners, Unterordners oder Dokuments tun kann. Dieses System wird als <a href=\"https:\/\/nextcloud.com\/blog\/access-control-lists\/\">Access Control List<\/a> bezeichnet und erm\u00f6glicht es dem Administrator, festzulegen, wer einen Ordner oder ein Dokument lesen, schreiben, erstellen, l\u00f6schen, freigeben und herunterladen darf. Gruppenordner geben den Administratoren die n\u00f6tige Autorit\u00e4t und schaffen gleichzeitig ein kollaboratives Umfeld f\u00fcr die Mitarbeiter.<\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<p class=\"wp-block-paragraph\">Erfahren Sie mehr \u00fcber die AWO Berlin-Mitte und ihre Aufgaben auf ihrer <a href=\"https:\/\/awo-mitte.de\/\">Website.<\/a><\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/01\/Logo-1024x475.png\" alt=\"\" class=\"wp-image-92510\" width=\"694\" height=\"321\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2023\/01\/Logo-1024x475.png 1024w, https:\/\/nextcloud.com\/c\/uploads\/2023\/01\/Logo-300x139.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2023\/01\/Logo-768x356.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2023\/01\/Logo-1536x712.png 1536w, https:\/\/nextcloud.com\/c\/uploads\/2023\/01\/Logo-2048x949.png 2048w\" sizes=\"(max-width: 694px) 100vw, 694px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Was halten Sie von diesem Anwendungsfall?<\/p>\n\n<p class=\"wp-block-paragraph\">Wenn Sie der Meinung sind, dass Ihr Unternehmen \u00e4hnliche Dateispeicher, Kollaborationstools und Prozesse ben\u00f6tigt, sollten Sie sich unsere Seite <a href=\"https:\/\/nextcloud.com\/enterprise\/\">Nextcloud f\u00fcr Unternehmen <\/a>ansehen oder sich von einem Nextcloud-Experten <a href=\"https:\/\/nextcloud.com\/contact\/\">kontaktieren<\/a> lassen.<\/p>\n\n<p class=\"wp-block-paragraph\">Fordern Sie noch heute eine sofortige <a href=\"https:\/\/nextcloud.com\/instant-trial\/\">Testversion<\/a>, einen <a href=\"https:\/\/nextcloud.com\/de\/ein-proof-of-concept-anfordern\/\">Proof of Concept<\/a> oder ein <a href=\"https:\/\/nextcloud.com\/get-a-quote\/\">Angebot<\/a> an!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bei der AWO Berlin-Mitte arbeiten 600 Teammitglieder mit Nextcloud Hub und nutzen Files, Talk, Deck, Tasks und mehr, um zu kommunizieren, zu teilen, zu planen und mit oft sehr kritischen, pers\u00f6nlichen Daten zusammenzuarbeiten. Lesen Sie weiter und erfahren Sie, warum sich die AWO f\u00fcr Nextcloud entschieden hat. Die AWO Berlin-Mitte ist ein gro\u00dfer Anbieter von [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"publish_to_discourse":"","publish_post_category":"","wpdc_auto_publish_overridden":"","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"","discourse_permalink":"","wpdc_publishing_response":"","wpdc_publishing_error":"","footnotes":""},"categories":[276,277,228],"tags":[],"class_list":["post-93259","post","type-post","status-publish","format-standard","hentry","category-blog-de","category-clients","category-community-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>600 Mitarbeiter der Berliner NGO AWO arbeiten \u00fcber Nextcloud zusammen - Nextcloud<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nextcloud.com\/de\/blog\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"600 Mitarbeiter der Berliner NGO AWO arbeiten \u00fcber Nextcloud zusammen - Nextcloud\" \/>\n<meta property=\"og:description\" content=\"Bei der AWO Berlin-Mitte arbeiten 600 Teammitglieder mit Nextcloud Hub und nutzen Files, Talk, Deck, Tasks und mehr, um zu kommunizieren, zu teilen, zu planen und mit oft sehr kritischen, pers\u00f6nlichen Daten zusammenzuarbeiten. Lesen Sie weiter und erfahren Sie, warum sich die AWO f\u00fcr Nextcloud entschieden hat. Die AWO Berlin-Mitte ist ein gro\u00dfer Anbieter von [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nextcloud.com\/de\/blog\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\/\" \/>\n<meta property=\"og:site_name\" content=\"Nextcloud\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nextclouders\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-02T09:55:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-02T16:51:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/uber_uns_startseite.png\" \/>\n<meta name=\"author\" content=\"Mikaela Schneider\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mikaela Schneider\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/blog\\\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/blog\\\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\\\/\"},\"author\":{\"name\":\"Mikaela Schneider\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/#\\\/schema\\\/person\\\/ea95df24e6e3adc5f63c79555fa599f5\"},\"headline\":\"600 Mitarbeiter der Berliner NGO AWO arbeiten \u00fcber Nextcloud zusammen\",\"datePublished\":\"2023-02-02T09:55:38+00:00\",\"dateModified\":\"2023-02-02T16:51:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/blog\\\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\\\/\"},\"wordCount\":657,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/blog\\\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nextcloud.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/uber_uns_startseite.png\",\"articleSection\":[\"Blog\",\"Clients\",\"Community\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/nextcloud.com\\\/de\\\/blog\\\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/blog\\\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\\\/\",\"url\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/blog\\\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\\\/\",\"name\":\"600 Mitarbeiter der Berliner NGO AWO arbeiten \u00fcber Nextcloud zusammen - Nextcloud\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/blog\\\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/blog\\\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nextcloud.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/uber_uns_startseite.png\",\"datePublished\":\"2023-02-02T09:55:38+00:00\",\"dateModified\":\"2023-02-02T16:51:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/blog\\\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nextcloud.com\\\/de\\\/blog\\\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/blog\\\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nextcloud.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/uber_uns_startseite.png\",\"contentUrl\":\"https:\\\/\\\/nextcloud.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/uber_uns_startseite.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/blog\\\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"600 Mitarbeiter der Berliner NGO AWO arbeiten \u00fcber Nextcloud zusammen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/\",\"name\":\"Nextcloud\",\"description\":\"Regain control over your data\",\"publisher\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/#organization\",\"name\":\"Nextcloud\",\"url\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nextcloud.com\\\/c\\\/uploads\\\/2022\\\/10\\\/nextcloud-logo-blue-transparent.svg\",\"contentUrl\":\"https:\\\/\\\/nextcloud.com\\\/c\\\/uploads\\\/2022\\\/10\\\/nextcloud-logo-blue-transparent.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Nextcloud\"},\"image\":{\"@id\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nextclouders\\\/\",\"https:\\\/\\\/x.com\\\/nextclouders\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/10827569\\\/\",\"https:\\\/\\\/youtube.com\\\/nextcloud\",\"https:\\\/\\\/www.instagram.com\\\/nextclouders\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nextcloud.com\\\/de\\\/#\\\/schema\\\/person\\\/ea95df24e6e3adc5f63c79555fa599f5\",\"name\":\"Mikaela Schneider\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g\",\"caption\":\"Mikaela Schneider\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"600 Mitarbeiter der Berliner NGO AWO arbeiten \u00fcber Nextcloud zusammen - Nextcloud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nextcloud.com\/de\/blog\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\/","og_locale":"de_DE","og_type":"article","og_title":"600 Mitarbeiter der Berliner NGO AWO arbeiten \u00fcber Nextcloud zusammen - Nextcloud","og_description":"Bei der AWO Berlin-Mitte arbeiten 600 Teammitglieder mit Nextcloud Hub und nutzen Files, Talk, Deck, Tasks und mehr, um zu kommunizieren, zu teilen, zu planen und mit oft sehr kritischen, pers\u00f6nlichen Daten zusammenzuarbeiten. Lesen Sie weiter und erfahren Sie, warum sich die AWO f\u00fcr Nextcloud entschieden hat. Die AWO Berlin-Mitte ist ein gro\u00dfer Anbieter von [&hellip;]","og_url":"https:\/\/nextcloud.com\/de\/blog\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\/","og_site_name":"Nextcloud","article_publisher":"https:\/\/www.facebook.com\/Nextclouders\/","article_published_time":"2023-02-02T09:55:38+00:00","article_modified_time":"2023-02-02T16:51:19+00:00","og_image":[{"url":"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/uber_uns_startseite.png","type":"","width":"","height":""}],"author":"Mikaela Schneider","twitter_misc":{"Verfasst von":"Mikaela Schneider","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nextcloud.com\/de\/blog\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\/#article","isPartOf":{"@id":"https:\/\/nextcloud.com\/de\/blog\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\/"},"author":{"name":"Mikaela Schneider","@id":"https:\/\/nextcloud.com\/de\/#\/schema\/person\/ea95df24e6e3adc5f63c79555fa599f5"},"headline":"600 Mitarbeiter der Berliner NGO AWO arbeiten \u00fcber Nextcloud zusammen","datePublished":"2023-02-02T09:55:38+00:00","dateModified":"2023-02-02T16:51:19+00:00","mainEntityOfPage":{"@id":"https:\/\/nextcloud.com\/de\/blog\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\/"},"wordCount":657,"commentCount":0,"publisher":{"@id":"https:\/\/nextcloud.com\/de\/#organization"},"image":{"@id":"https:\/\/nextcloud.com\/de\/blog\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\/#primaryimage"},"thumbnailUrl":"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/uber_uns_startseite.png","articleSection":["Blog","Clients","Community"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nextcloud.com\/de\/blog\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nextcloud.com\/de\/blog\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\/","url":"https:\/\/nextcloud.com\/de\/blog\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\/","name":"600 Mitarbeiter der Berliner NGO AWO arbeiten \u00fcber Nextcloud zusammen - Nextcloud","isPartOf":{"@id":"https:\/\/nextcloud.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nextcloud.com\/de\/blog\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\/#primaryimage"},"image":{"@id":"https:\/\/nextcloud.com\/de\/blog\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\/#primaryimage"},"thumbnailUrl":"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/uber_uns_startseite.png","datePublished":"2023-02-02T09:55:38+00:00","dateModified":"2023-02-02T16:51:19+00:00","breadcrumb":{"@id":"https:\/\/nextcloud.com\/de\/blog\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nextcloud.com\/de\/blog\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nextcloud.com\/de\/blog\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\/#primaryimage","url":"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/uber_uns_startseite.png","contentUrl":"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/uber_uns_startseite.png"},{"@type":"BreadcrumbList","@id":"https:\/\/nextcloud.com\/de\/blog\/600-mitarbeiter-der-berliner-ngo-awo-arbeiten-ueber-nextcloud-zusammen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nextcloud.com\/de\/"},{"@type":"ListItem","position":2,"name":"600 Mitarbeiter der Berliner NGO AWO arbeiten \u00fcber Nextcloud zusammen"}]},{"@type":"WebSite","@id":"https:\/\/nextcloud.com\/de\/#website","url":"https:\/\/nextcloud.com\/de\/","name":"Nextcloud","description":"Regain control over your data","publisher":{"@id":"https:\/\/nextcloud.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nextcloud.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/nextcloud.com\/de\/#organization","name":"Nextcloud","url":"https:\/\/nextcloud.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nextcloud.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","contentUrl":"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","width":"1024","height":"1024","caption":"Nextcloud"},"image":{"@id":"https:\/\/nextcloud.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Nextclouders\/","https:\/\/x.com\/nextclouders","https:\/\/www.linkedin.com\/company\/10827569\/","https:\/\/youtube.com\/nextcloud","https:\/\/www.instagram.com\/nextclouders\/"]},{"@type":"Person","@id":"https:\/\/nextcloud.com\/de\/#\/schema\/person\/ea95df24e6e3adc5f63c79555fa599f5","name":"Mikaela Schneider","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g","caption":"Mikaela Schneider"}}]}},"featured_media_url":false,"_links":{"self":[{"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/posts\/93259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/comments?post=93259"}],"version-history":[{"count":0,"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/posts\/93259\/revisions"}],"wp:attachment":[{"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/media?parent=93259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/categories?post=93259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/tags?post=93259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}