{"id":349022,"date":"2025-11-27T09:00:00","date_gmt":"2025-11-27T08:00:00","guid":{"rendered":"https:\/\/nextcloud.com\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/"},"modified":"2025-12-11T15:02:12","modified_gmt":"2025-12-11T14:02:12","slug":"der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt","status":"publish","type":"post","link":"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/","title":{"rendered":"Der erste Open-Source-KI-Assistent, der Ihre Privatsph\u00e4re sch\u00fctzt"},"content":{"rendered":"\n<p>KI-Technologie unterst\u00fctzt uns mittlerweile in vielen Bereichen und ist \u00fcberall zug\u00e4nglich, sodass wir sie nicht mehr ignorieren k\u00f6nnen. Daher entscheiden sich immer mehr Nutzer, die Privatsph\u00e4re von morgen zugunsten des herausragenden Ergebnisses von heute zu opfern.<\/p>\n\n\n\n<p>Wir bei Nextcloud sind \u00fcberzeugt, dass jeder Nutzer seine Privatsph\u00e4re verdient. Wir haben den <a href=\"https:\/\/nextcloud.com\/de\/assistant\/\" target=\"_blank\" rel=\"noreferrer noopener\">ersten Open-Source-KI-Assistenten<\/a> ver\u00f6ffentlicht, der an dem Ort gehostet wird, den Sie sich f\u00fcr Ihre Daten w\u00fcnschen. Er kann viele Aufgaben in Ihrer Kollaborationsplattform erledigen, ohne Ihre Daten zu gef\u00e4hrden: Beispiele sind das Verfassen von Inhalten, die E-Mail-Kommunikation oder Team-Chats. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Einf\u00fchrung von Nextcloud Assistant<\/h2>\n\n\n\n<p>Nextcloud Assistant ist ein leistungsf\u00e4higes und vielseitiges Tool, mit dem Sie Ihre Arbeit in <a href=\"https:\/\/nextcloud.com\/de\/hub\/\" target=\"_blank\" rel=\"noreferrer noopener\">Nextcloud\u00a0Hub<\/a> optimieren k\u00f6nnen, sodass Sie das Verfassen von Texten, die Kommunikation und andere Produktivit\u00e4tsaufgaben einfach und mit geringem Aufwand erledigen k\u00f6nnen.<\/p>\n\n\n\n<p>Im Gegensatz zu anderen KI-gest\u00fctzten Tools f\u00fcr Zusammenarbeit an Inhalten gibt Nextcloud Ihre Daten nicht an Drittanbieter weiter, um das zugrunde liegende KI-Modell zu trainieren. Alle Daten, mit denen Sie arbeiten, einschlie\u00dflich Dokumente, E-Mails und Chats, bleiben daher in Ihrem Besitz.<\/p>\n\n\n<section class=\"nc-note-section\" id=\"\">\r\n\t<div class=\"\">\r\n\t\t<div class=\"row\">\r\n\t\t\t\t\t\t\t<div class=\"col-lg-12\">\r\n\t\t\t\t\t\t\t<div class=\"text-block\">\r\n\t\t\t\t\t<h3>Wie erreichen wir das?<\/h3>\n<p>Wir entwickeln den KI-Assistenten mit einem flexiblen Ansatz, der unabh\u00e4ngig von einzelnen Anbietern funktioniert und Ihnen die Wahl zwischen mehreren gro\u00dfen Sprachmodellen (LLM) und Diensten bietet. Er kann vollst\u00e4ndig innerhalb Ihrer Instanz gehostet werden, alle Anfragen intern bearbeiten oder von einem externen Dienst betrieben werden. Dies erm\u00f6glicht herausragende Sprachverarbeitungsf\u00e4higkeiten in verschiedensten Anwendungsszenarien \u2013 bei vollst\u00e4ndiger Transparenz und Kontrolle \u00fcber alle Hintergrundprozesse. Und das Beste: Sie profitieren von einem KI-Assistenten, der zu 100% auf Open-Source-Technologie setzt.<\/p>\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t\t\t\r\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/section>\n\n\n<p>Nextcloud Assistant-Funktionen sind in der Hauptnavigation des Nextcloud Hubs verf\u00fcgbar, um Ihnen bei schnellen Textaufgaben zu helfen. In einigen Apps, zum Beispiel Nextcloud Text, Nextcloud Mail und Nextcloud Talk, gibt es sogar app-spezifische Aktionen.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Hub 10 Nextcloud Assistant 3.0: AI with agency features that respects your privacy\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/2aIzzRmamkw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Wenn Sie mehr \u00fcber andere KI-Tools erfahren m\u00f6chten, die in Nextcloud verf\u00fcgbar sind, finden Sie weitere Informationen in unserem \u00dcberblick \u00fcber die <a href=\"https:\/\/nextcloud.com\/blog\/ai-in-nextcloud-what-why-and-how\/\">KI-Funktionen<\/a> oder in unserem <a href=\"https:\/\/docs.nextcloud.com\/server\/latest\/admin_manual\/ai\/index.html\" target=\"_blank\" rel=\"noreferrer noopener\">Dokumentationsportal<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a><\/a>Schnellzugriff \u00fcber die Navigationsleiste<\/h3>\n\n\n\n<p>Woran auch immer Sie arbeiten \u2013 Nextcloud Assistant ist nur einen Klick entfernt. Wenn Sie bei kleineren Aufgaben wie dem Generieren einer \u00dcberschrift, Zusammenfassen eines Textes oder \u00dcbersetzen eines Satzes Hilfe ben\u00f6tigen, klicken Sie einfach auf das \u2728-Symbol in der oberen rechten Ecke der Hauptnavigation und geben die gew\u00fcnschten Daten in den Assistenten ein.<\/p>\n\n\n\n<p>Mit jeder neuen Version von Nextcloud Hub werden weitere Tools unterst\u00fctzt. Schauen Sie sich auch unseren Release Blog zu <a href=\"https:\/\/nextcloud.com\/de\/blog\/nextcloud-hub-25-autumn\/\" target=\"_blank\" rel=\"noreferrer noopener\">Nextcloud Hub 25 Autumn<\/a> an, um die neuesten Funktionen zu finden!<\/p>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile imageRoundShadow\"><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\">Chatten Sie mit dem Nextcloud-Assistenten <\/h3>\n\n\n\n<p>Der Nextcloud-Assistent wird mit einer Chat-Schnittstelle noch komfortabler. Hier k\u00f6nnen Sie Prompts eingeben und Fragen in einem Dialogformat stellen. Er merkt sich Ihre Gespr\u00e4che, wodurch Sie nat\u00fcrlich und reibungslos mit dem Assistenten interagieren. Unterhalten Sie sich \u00fcber Ihren Tag, arbeiten Sie an der n\u00e4chsten Pressemitteilung oder lesen Sie Ihre Social-Media-Beitr\u00e4ge Korrektur. Alles lokal auf Ihrem Server und ohne Datenlecks!<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"3567\" height=\"2378\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Hub-9-AI-ChatUI-assistant-cropped.png\" alt=\"Nextcloud Hub 9 AI \u2013 ChatUI Nextcloud-Assistent \u2013 abgeschnitten\" class=\"wp-image-253636 size-full\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Hub-9-AI-ChatUI-assistant-cropped.png 3567w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Hub-9-AI-ChatUI-assistant-cropped-300x200.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Hub-9-AI-ChatUI-assistant-cropped-864x576.png 864w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Hub-9-AI-ChatUI-assistant-cropped-768x512.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Hub-9-AI-ChatUI-assistant-cropped-1536x1024.png 1536w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Hub-9-AI-ChatUI-assistant-cropped-2048x1365.png 2048w\" sizes=\"(max-width: 3567px) 100vw, 3567px\" \/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Durchsuchen Sie mit dem Assistenten Ihre eigenen Dateien <\/h3>\n\n\n\n<p>Sie k\u00f6nnen Nextcloud Assistant mit dem Feature Kontext-Chat nach Ihren eigenen Daten fragen. Nextcloud Assistant kann auf Daten verschiedener Apps zugreifen, zum Beispiel Nextcloud Files, Nextcloud Collectives und sogar der Analytics-App.<\/p>\n\n\n<section class=\"simple-slider-section \" id=\"\">\r\n\t<div class=\"\">\r\n                    <div class=\"owl-carousel simple_slider_slideshow\" id=\"\">\r\n                                    <div class=\"gallery_item\" id=\"354623\">\r\n                        <a href=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Chat-\u2013-example-request-.png\" class=\"simple_slider_slideshow_link\">\r\n                            <img decoding=\"async\" width=\"1920\" height=\"1095\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Chat-\u2013-example-request-.png\" class=\"attachment-full size-full\" alt=\"Nextcloud Assistant screenshot Context Chat \u2013 example request\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Chat-\u2013-example-request-.png 1920w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Chat-\u2013-example-request--300x171.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Chat-\u2013-example-request--1010x576.png 1010w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Chat-\u2013-example-request--768x438.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Chat-\u2013-example-request--1536x876.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>                        <\/a>\r\n                                            <\/div>\r\n                                    <div class=\"gallery_item\" id=\"354615\">\r\n                        <a href=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant_screenshot_ConextChat-1.png\" class=\"simple_slider_slideshow_link\">\r\n                            <img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant_screenshot_ConextChat-1.png\" class=\"attachment-full size-full\" alt=\"Nextcloud Assistant screenshot - C\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant_screenshot_ConextChat-1.png 1920w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant_screenshot_ConextChat-1-300x169.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant_screenshot_ConextChat-1-1024x576.png 1024w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant_screenshot_ConextChat-1-768x432.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant_screenshot_ConextChat-1-1536x864.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>                        <\/a>\r\n                                            <\/div>\r\n                                    <div class=\"gallery_item\" id=\"258799\">\r\n                        <a href=\"https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/context-chat-answering-question-about-data-from-analytics-app-1.png\" class=\"simple_slider_slideshow_link\">\r\n                            <img decoding=\"async\" width=\"6400\" height=\"3600\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/context-chat-answering-question-about-data-from-analytics-app-1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/context-chat-answering-question-about-data-from-analytics-app-1.png 6400w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Context-Chat-answering-question-about-data-from-Analytics-app-300x169.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Context-Chat-answering-question-about-data-from-Analytics-app-768x432.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Context-Chat-answering-question-about-data-from-Analytics-app-1024x576.png 1024w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Context-Chat-answering-question-about-data-from-Analytics-app-1536x864.png 1536w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Context-Chat-answering-question-about-data-from-Analytics-app-2048x1152.png 2048w\" sizes=\"(max-width: 6400px) 100vw, 6400px\" \/>                        <\/a>\r\n                                            <\/div>\r\n                            <\/ul>\r\n        \t<\/div>\r\n<\/section>\r\n<script>\r\n    jQuery(document).ready(function ($) {\r\n        var owl_simple_slider = $('.simple_slider_slideshow');\r\n        owl_simple_slider.owlCarousel({\r\n            loop: false,\r\n            stagePadding: 50,\r\n            autoplay: true,\r\n            margin:10,\r\n            dots: false,\r\n            nav:true,\r\n            responsive:{\r\n                0:{\r\n                    items:1\r\n                },\r\n                600:{\r\n                    items:1\r\n                },\r\n                800:{\r\n                    items:1\r\n                },\r\n                1000:{\r\n                    items:1\r\n                }\r\n            },\r\n            onDragged: owl_stop_autoplay,\r\n            autoplayHoverPause:true,\r\n            onInitialized: function (event) {\r\n\t\t\t\t\/\/ Remove role=\"presentation\" from arrows\r\n\t\t\t\t$('.owl-prev, .owl-next').removeAttr('role');\r\n\t\t\t\t$('.owl-prev, .owl-next').attr('tabindex', 0);\r\n\t\t\t}\r\n        });\r\n\r\n        \/\/ Assign original indices to real (non-cloned) items\r\n\t\towl_simple_slider.find('.owl-item:not(.cloned)').each(function (i) {\r\n\t\t\t$(this).attr('data-original-index', i);\r\n\t\t});\r\n\r\n\t\t\/\/ Focus handling for links, buttons, inputs, etc.\r\n\t\towl_simple_slider.on('focusin', '.owl-item a, .owl-item button, .owl-item input', function () {\r\n\t\t\tconst $focusedItem = $(this).closest('.owl-item');\r\n\r\n\t\t\tif (!$focusedItem.length || $focusedItem.hasClass('cloned')) {\r\n\t\t\t\/\/ Try to find the real item (not a clone)\r\n\t\t\tconst realIndex = $focusedItem.data('original-index');\r\n\t\t\tif (typeof realIndex !== 'undefined') {\r\n\t\t\t\towl_simple_slider.trigger('to.owl.carousel', [realIndex, 300, true]);\r\n\t\t\t}\r\n\t\t\treturn;\r\n\t\t\t}\r\n\r\n\t\t\tconst index = $focusedItem.data('original-index');\r\n\t\t\tif (typeof index !== 'undefined') {\r\n\t\t\towl_simple_slider.trigger('to.owl.carousel', [index, 300, true]);\r\n\t\t\t}\r\n\t\t});\r\n\r\n        owl_simple_slider.on('click', function(e) {\r\n            owl_stop_autoplay();\r\n        });\r\n        function owl_stop_autoplay() {\r\n            \/\/console.log('autoplay stopped.');\r\n            owl_simple_slider.trigger('stop.owl.autoplay');\r\n        }\r\n\r\n    });\r\n<\/script>\r\n\n\n\n<p>Es beantwortet Fragen zu Ihren Dokumenten und Assets oder findet Elemente in Ihren Apps, wie z. B. einzelne Dateien. Sie k\u00f6nnen den Umfang manuell definieren und sogar auf einen bestimmten Ordner oder eine bestimmte Datei begrenzen, um noch genauer zu arbeiten.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Nextcloud Assistant File summaries\" src=\"https:\/\/player.vimeo.com\/video\/1119034662?h=95390e5d14&amp;dnt=1&amp;app_id=122963\" width=\"500\" height=\"281\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Funktionen des KI-Agenten: Bitten Sie ihn, Aktionen f\u00fcr Sie auszuf\u00fchren<\/h3>\n\n\n\n<p>Die <a href=\"https:\/\/nextcloud.com\/blog\/how-to-automate-tasks-with-open-source-ai-agent-tools-in-nextcloud-assistant\/\" target=\"_blank\" rel=\"noreferrer noopener\">Funktionen des KI-Agenten<\/a> machen den Nextcloud Assistant noch st\u00e4rker zu Ihrem pers\u00f6nlichen Assistenten. Zum Beispiel k\u00f6nnen Sie ihn bitten, ein Kalenderereignis zu erstellen, eine Chatnachricht in Nextcloud Talk zu senden oder das Wetter f\u00fcr Sie zu \u00fcberpr\u00fcfen. <\/p>\n\n\n\n<p>Oder vielleicht etwas Komplexeres? <\/p>\n\n\n\n<p>Suchen Sie zum Beispiel in Nextcloud Talk nach einem Gespr\u00e4ch mit einem Kollegen, finden Sie heraus, welches Dokument Sie versprochen haben zu erstellen, und bitten Sie Nextcloud Assistant, eine Vorlage daf\u00fcr zu erstellen, um Ihnen den Einstieg in die Aufgabe zu erleichtern.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Nextcloud Assistant AI Agency\" src=\"https:\/\/player.vimeo.com\/video\/1117801102?h=7b68fe6f31&amp;dnt=1&amp;app_id=122963\" width=\"500\" height=\"281\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Weitere Details zur Einrichtung und Nutzung von KI-Agenten-Tools sowie zu allen derzeit unterst\u00fctzten Aktionen finden Sie in der <a href=\"https:\/\/docs.nextcloud.com\/server\/latest\/admin_manual\/ai\/app_context_agent.html\" target=\"_blank\" rel=\"noreferrer noopener\">Dokumentation<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Werkzeuge f\u00fcr Schreibhilfe und Textgenerierung<\/h3>\n\n\n\n<p>Dank des KI-Assistenten unterst\u00fctzt Sie Nextcloud Text sicher dabei, Ihre Texte klarer, pr\u00e4ziser und professioneller zu gestalten. Das Tool steht Ihnen auch direkt in den Editoren der Nextcloud-Office-Apps zur Verf\u00fcgung und bewahrt Sie vor Ablenkungen und zu vielen offenen Tabs.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full imageRoundShadow\"><img decoding=\"async\" width=\"2560\" height=\"1459\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-in-Nextcloud-Text-scaled.png\" alt=\"Nextcloud Assistant in Nextcloud Text\" class=\"wp-image-354716\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-in-Nextcloud-Text-scaled.png 2560w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-in-Nextcloud-Text-300x171.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-in-Nextcloud-Text-1010x576.png 1010w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-in-Nextcloud-Text-768x438.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-in-Nextcloud-Text-1536x876.png 1536w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-in-Nextcloud-Text-2048x1168.png 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<p>Beispiele f\u00fcr verf\u00fcgbare Funktionen beim Arbeiten mit Text:<\/p>\n\n\n\n<ul class=\"wp-block-list nc-list\">\n<li>Einen Text oder eine \u00dcberschrift aus dem Text generieren<\/li>\n\n\n\n<li>Zusammenfassen<\/li>\n\n\n\n<li>Neu formulieren<\/li>\n\n\n\n<li>Tonwechsel<\/li>\n\n\n\n<li>Korrektur lesen<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full imageRoundShadow\"><img decoding=\"async\" width=\"1920\" height=\"1093\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-\u2013-work-with-text-features-1.png\" alt=\"Nextcloud Assistant \u2013 Funktionen f\u00fcr das Arbeiten mit Text:\" class=\"wp-image-354707\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-\u2013-work-with-text-features-1.png 1920w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-\u2013-work-with-text-features-1-300x171.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-\u2013-work-with-text-features-1-1012x576.png 1012w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-\u2013-work-with-text-features-1-768x437.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-\u2013-work-with-text-features-1-1536x874.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Dateierstellung: Dokumente, Pr\u00e4sentationen, Tabellenkalkulationen und PDFs<\/h4>\n\n\n\n<p>Mit einem einfachen Prompt k\u00f6nnen Sie Dokumente, Tabellenkalkulationen, Pr\u00e4sentationen und sogar PDFs mit KI erstellen. Erstellen Sie zum Beispiel eine Tabelle f\u00fcr Ihr n\u00e4chstes Produktmeeting oder erhalten Sie einen kurzen \u00dcberblick \u00fcber alle Ihre Support-Tickets. Geben Sie dem KI-Assistenten eine grobe Idee oder eine erste Gliederung Ihrer Pr\u00e4sentation, und er verschafft Ihnen einen starken Einstieg.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Nextcloud Assistant document generation\" src=\"https:\/\/player.vimeo.com\/video\/1118133193?h=923055797a&amp;dnt=1&amp;app_id=122963\" width=\"500\" height=\"281\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Texte in Ihrem pers\u00f6nlichen Stil durch kontextuelles Schreiben<\/h4>\n\n\n\n<p>Kontextuelles Schreiben ist eine weitere kontextbasierte Funktion des Nextcloud-Assistenten. Sie kann Kontext aus vorhandenen Dateien ableiten, um den einzigartigen Ton, die Formulierung und sogar die Struktur aus diesen Dateien zu vermitteln. Auf diese Weise entstehen anhand der von Ihnen bereitgestellten Daten neue Texte.<\/p>\n\n\n\n<p>Teilen Sie dem Nextcloud-Assistenten Ihre Berufserfahrung mit und stellen Sie ihm Ihren Lebenslauf als Datei zur Verf\u00fcgung \u2013 er erstellt dann einen ma\u00dfgeschneiderten Lebenslauf f\u00fcr Sie. Sie k\u00f6nnen Notizen aus einer Besprechung oder das generierte Transkript eines Videoanrufs in Talk teilen. Oder geben Sie einen Bericht frei, der ganz nach Ihren Vorstellungen erstellt wurde. Der Assistent macht sich an die Arbeit und erstellt einen Bericht, der Ihrem Referenzbericht nachempfunden ist. <\/p>\n\n\n\n<p>Jetzt nur noch \u00fcberpr\u00fcfen \u2013 und fertig!<\/p>\n\n\n<section class=\"simple-slider-section \" id=\"\">\r\n\t<div class=\"\">\r\n                    <div class=\"owl-carousel simple_slider_slideshow\" id=\"\">\r\n                                    <div class=\"gallery_item\" id=\"354646\">\r\n                        <a href=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-with-empty-fields.png\" class=\"simple_slider_slideshow_link\">\r\n                            <img decoding=\"async\" width=\"1920\" height=\"1093\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-with-empty-fields.png\" class=\"attachment-full size-full\" alt=\"Nextcloud Assistant screenshot Context Write with empty fields\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-with-empty-fields.png 1920w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-with-empty-fields-300x171.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-with-empty-fields-1012x576.png 1012w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-with-empty-fields-768x437.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-with-empty-fields-1536x874.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>                        <\/a>\r\n                                            <\/div>\r\n                                    <div class=\"gallery_item\" id=\"354651\">\r\n                        <a href=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-with-filled-fields.png\" class=\"simple_slider_slideshow_link\">\r\n                            <img decoding=\"async\" width=\"1920\" height=\"1095\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-with-filled-fields.png\" class=\"attachment-full size-full\" alt=\"Nextcloud Assistant screenshot Context Write with filled fields\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-with-filled-fields.png 1920w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-with-filled-fields-300x171.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-with-filled-fields-1010x576.png 1010w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-with-filled-fields-768x438.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-with-filled-fields-1536x876.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>                        <\/a>\r\n                                            <\/div>\r\n                                    <div class=\"gallery_item\" id=\"354641\">\r\n                        <a href=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-result.png\" class=\"simple_slider_slideshow_link\">\r\n                            <img decoding=\"async\" width=\"1920\" height=\"1095\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-result.png\" class=\"attachment-full size-full\" alt=\"Nextcloud Assistant screenshot Context Write result\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-result.png 1920w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-result-300x171.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-result-1010x576.png 1010w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-result-768x438.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Assistant-screenshot-Context-Write-result-1536x876.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>                        <\/a>\r\n                                            <\/div>\r\n                            <\/ul>\r\n        \t<\/div>\r\n<\/section>\r\n<script>\r\n    jQuery(document).ready(function ($) {\r\n        var owl_simple_slider = $('.simple_slider_slideshow');\r\n        owl_simple_slider.owlCarousel({\r\n            loop: false,\r\n            stagePadding: 50,\r\n            autoplay: true,\r\n            margin:10,\r\n            dots: false,\r\n            nav:true,\r\n            responsive:{\r\n                0:{\r\n                    items:1\r\n                },\r\n                600:{\r\n                    items:1\r\n                },\r\n                800:{\r\n                    items:1\r\n                },\r\n                1000:{\r\n                    items:1\r\n                }\r\n            },\r\n            onDragged: owl_stop_autoplay,\r\n            autoplayHoverPause:true,\r\n            onInitialized: function (event) {\r\n\t\t\t\t\/\/ Remove role=\"presentation\" from arrows\r\n\t\t\t\t$('.owl-prev, .owl-next').removeAttr('role');\r\n\t\t\t\t$('.owl-prev, .owl-next').attr('tabindex', 0);\r\n\t\t\t}\r\n        });\r\n\r\n        \/\/ Assign original indices to real (non-cloned) items\r\n\t\towl_simple_slider.find('.owl-item:not(.cloned)').each(function (i) {\r\n\t\t\t$(this).attr('data-original-index', i);\r\n\t\t});\r\n\r\n\t\t\/\/ Focus handling for links, buttons, inputs, etc.\r\n\t\towl_simple_slider.on('focusin', '.owl-item a, .owl-item button, .owl-item input', function () {\r\n\t\t\tconst $focusedItem = $(this).closest('.owl-item');\r\n\r\n\t\t\tif (!$focusedItem.length || $focusedItem.hasClass('cloned')) {\r\n\t\t\t\/\/ Try to find the real item (not a clone)\r\n\t\t\tconst realIndex = $focusedItem.data('original-index');\r\n\t\t\tif (typeof realIndex !== 'undefined') {\r\n\t\t\t\towl_simple_slider.trigger('to.owl.carousel', [realIndex, 300, true]);\r\n\t\t\t}\r\n\t\t\treturn;\r\n\t\t\t}\r\n\r\n\t\t\tconst index = $focusedItem.data('original-index');\r\n\t\t\tif (typeof index !== 'undefined') {\r\n\t\t\towl_simple_slider.trigger('to.owl.carousel', [index, 300, true]);\r\n\t\t\t}\r\n\t\t});\r\n\r\n        owl_simple_slider.on('click', function(e) {\r\n            owl_stop_autoplay();\r\n        });\r\n        function owl_stop_autoplay() {\r\n            \/\/console.log('autoplay stopped.');\r\n            owl_simple_slider.trigger('stop.owl.autoplay');\r\n        }\r\n\r\n    });\r\n<\/script>\r\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile imageRoundShadow\"><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">\u00dcbersetzen mit KI<\/h4>\n\n\n\n<p>Die KI-\u00dcbersetzung ist direkt im Nextcloud Assistant-Men\u00fc verf\u00fcgbar. Die \u00dcbersetzungsm\u00f6glichkeiten sind jetzt nahezu unbegrenzt, da wir Unterst\u00fctzung f\u00fcr Hunderte von Sprachen hinzugef\u00fcgt haben, die die App erkennen, lesen und \u00fcbersetzen kann.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Hub-9-AI-More-language-support-for-Assistant-w-translation-cropped.png\"><img decoding=\"async\" width=\"1024\" height=\"412\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Hub-9-AI-More-language-support-for-Assistant-w-translation-cropped-1024x412.png\" alt=\"Nextcloud Hub 9 AI \u2013 Unterst\u00fctzung weiterer Sprachen im Assistenten\" class=\"wp-image-253631 size-full\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Hub-9-AI-More-language-support-for-Assistant-w-translation-cropped-1024x412.png 1024w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Hub-9-AI-More-language-support-for-Assistant-w-translation-cropped-300x121.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Hub-9-AI-More-language-support-for-Assistant-w-translation-cropped-768x309.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Hub-9-AI-More-language-support-for-Assistant-w-translation-cropped-1536x618.png 1536w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Hub-9-AI-More-language-support-for-Assistant-w-translation-cropped-2048x825.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Zusammenfassungen, Antworten und Erinnerungen in Nextcloud Mail<\/h3>\n\n\n\n<p>Der Nextcloud Assistant fasst umfangreiche E-Mail-Verl\u00e4ufe f\u00fcr Sie zusammen, sodass Sie beim Suchen in Ihren Unterhaltungen in <a href=\"https:\/\/nextcloud.com\/de\/groupware\/\" target=\"_blank\" rel=\"noreferrer noopener\">Nextcloud Mail<\/a> eine ordentliche Menge Zeit sparen. Alle vorhandenen Aufgaben, Vorschl\u00e4ge und Fragen werden \u00fcbersichtlich und pr\u00e4zise dargestellt. Auf diese Weise erhalten Sie eine genaue Vorstellung vom gesamten Verlauf der Kommunikation.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full imageRoundShadow\"><a href=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant-in-Mail.png\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant-in-Mail.png\" alt=\"Nextcloud Assistant-Screenshot \u2013 Assistent in Nextcloud Mail\" class=\"wp-image-354588\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant-in-Mail.png 1920w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant-in-Mail-300x169.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant-in-Mail-1024x576.png 1024w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant-in-Mail-768x432.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant-in-Mail-1536x864.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure>\n\n\n\n<p>Der Nextcloud-Assistent generiert auch schnelle Antwortvorschl\u00e4ge auf Ihre eingehenden E-Mails basierend auf den E-Mail-Texten. Sie k\u00f6nnen die E-Mails dann blitzschnell beantworten.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full imageRoundShadow\"><img decoding=\"async\" width=\"1920\" height=\"1096\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Mail-AI-suggestions.png\" alt=\"Nextcloud Mail KI-Vorschl\u00e4ge\" class=\"wp-image-354671\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Mail-AI-suggestions.png 1920w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Mail-AI-suggestions-300x171.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Mail-AI-suggestions-1009x576.png 1009w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Mail-AI-suggestions-768x438.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Nextcloud-Mail-AI-suggestions-1536x877.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<p>Au\u00dferdem kann der Nextcloud-Assistent ermitteln, ob der Absender einer E-Mail eine Antwort erwartet: Wenn er feststellt, dass eine E-Mail nachverfolgt werden muss, wird diese Nachricht im Abschnitt <em>Nachverfolgung<\/em> platziert. Auf diese Weise ist sichergestellt, dass Sie diese E-Mail nicht vergessen.<\/p>\n\n\n<section class=\"nc-note-section\" id=\"\">\r\n\t<div class=\"\">\r\n\t\t<div class=\"row\">\r\n\t\t\t\t\t\t\t<div class=\"col-lg-12\">\r\n\t\t\t\t\t\t\t<div class=\"text-block\">\r\n\t\t\t\t\t<p>Brauchen Sie Hilfe bei den Antworten? \u00d6ffnen Sie den KI-Assistenten \u00fcber die obere Werkzeugleiste, um Antworten nach Ihren Vorgaben zu erstellen oder Ihr Schreiben zu verbessern.<\/p>\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t\t\t\r\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/section>\n\n\n<h3 class=\"wp-block-heading\">Automatische Erstellung von Terminen in Nextcloud\u00a0Kalender<\/h3>\n\n\n\n<p>Sie k\u00f6nnen aus Ihren E-Mails direkt Kalenderereignisse in der Nextcloud Mail-App erstellen. Der Nextcloud-Assistent generiert automatisch Titel und Beschreibungen und sogar die Agenda f\u00fcr diese Termine.\u00a0Kein Hin und Her mehr, um Besprechungen und Erinnerungen einzurichten!<\/p>\n\n\n\n<figure class=\"wp-block-image size-full imageRoundShadow\"><img decoding=\"async\" width=\"3024\" height=\"1726\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Mail-create-event-with-AI.png\" alt=\"Nextcloud Mail erstellt mit KI einen Termin\" class=\"wp-image-258198\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Mail-create-event-with-AI.png 3024w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Mail-create-event-with-AI-300x171.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Mail-create-event-with-AI-1009x576.png 1009w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Mail-create-event-with-AI-768x438.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Mail-create-event-with-AI-1536x877.png 1536w, https:\/\/nextcloud.com\/c\/uploads\/2024\/09\/Nextcloud-Mail-create-event-with-AI-2048x1169.png 2048w\" sizes=\"(max-width: 3024px) 100vw, 3024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Smarte Kommunikation in Talk<\/h3>\n\n\n\n<p>Nextcloud Assistant ist nahtlos integriert in <a href=\"https:\/\/nextcloud.com\/de\/talk\/\" target=\"_blank\" rel=\"noreferrer noopener\">Nextcloud Talk<\/a>. Wir haben den Assistenten vor dem Hintergrund der Optimierung Ihrer beruflichen Konversationen konzipiert: Ihr Team soll beim Brainstorming, bei der Planung und beim klaren Formulieren von Ideen unterst\u00fctzt werden.<\/p>\n\n\n\n<p>Zuallererst sorgt der Assistent f\u00fcr einen reibungslosen Gespr\u00e4chsverlauf, indem er Nachrichten \u00fcbersetzt, Texte schreibt und w\u00e4hrend des Chats Bilder sowie Aufkleber generiert. Einige dieser Funktionen sind \u00fcber Smart Picker verf\u00fcgbar. (Geben Sie \u201e\/\u201c ein und sehen Sie sich die beeindruckenden Ergebnisse an!)<\/p>\n\n\n\n<figure class=\"wp-block-image size-full imageRoundShadow\"><a href=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant-in-Talk.png\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant-in-Talk.png\" alt=\"Nextcloud Assistant-Screenshot \u2013 Assistent in Nextcloud Talk\" class=\"wp-image-354593\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant-in-Talk.png 1920w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant-in-Talk-300x169.png 300w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant-in-Talk-1024x576.png 1024w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant-in-Talk-768x432.png 768w, https:\/\/nextcloud.com\/c\/uploads\/2025\/11\/Assistant-in-Talk-1536x864.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Zusammenfassungen von Unterhaltungen<\/h4>\n\n\n\n<p>Nextcloud Assistant gibt Ihnen eine Chat-Zusammenfassung, wenn viele ungelesene Nachrichten schnell aufgeholt werden m\u00fcssen. Es kann auch Anruftranskripte f\u00fcr Sie erstellen und Ihre aufgezeichneten Anrufe automatisch basierend auf diesen Transkripten zusammenfassen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full imageRoundShadow\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/02\/Nextcloud-Talk-AI-summary-web.jpg\" alt=\"Chat-Zusammenfassung durch KI in Nextcloud Talk \" class=\"wp-image-290451\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2025\/02\/Nextcloud-Talk-AI-summary-web.jpg 1920w, https:\/\/nextcloud.com\/c\/uploads\/2025\/02\/Nextcloud-Talk-AI-summary-web-300x169.jpg 300w, https:\/\/nextcloud.com\/c\/uploads\/2025\/02\/Nextcloud-Talk-AI-summary-web-1024x576.jpg 1024w, https:\/\/nextcloud.com\/c\/uploads\/2025\/02\/Nextcloud-Talk-AI-summary-web-768x432.jpg 768w, https:\/\/nextcloud.com\/c\/uploads\/2025\/02\/Nextcloud-Talk-AI-summary-web-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Live-Transkriptionen in Meetings<\/h4>\n\n\n\n<p>Aktivieren Sie KI-gest\u00fctzte Transkriptionen in Nextcloud Talk-Meetings, damit Sprecher verst\u00e4ndlicher werden, oder folgen Sie dem Gespr\u00e4ch lautlos weiter, wenn Sie den Ton ausschalten m\u00fcssen. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Nextcloud Talk live AI transcriptions\" src=\"https:\/\/player.vimeo.com\/video\/1118134515?h=88b1210fe3&amp;dnt=1&amp;app_id=122963\" width=\"500\" height=\"281\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Schnelle Aktionen in Nextcloud Files<\/h3>\n\n\n\n<p>Bitten Sie den Assistenten, Ihre Dokumente zusammenzufassen oder Transkriptionen von Audiodateien direkt aus dem Kontextmen\u00fc Ihrer Datei zu erhalten.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Nextcloud Assistant File summaries\" src=\"https:\/\/player.vimeo.com\/video\/1119034662?h=95390e5d14&amp;dnt=1&amp;app_id=122963\" width=\"500\" height=\"281\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Vollst\u00e4ndige Verarbeitung von Daten auf Ihrem Server<\/h2>\n\n\n\n<p>Bei allem, was wir tun, verpflichtet sich Nextcloud zu Transparenz und Vertrauen. Wir haben hart daran gearbeitet, Komfort mit einem verantwortungsvollen Umgang mit Ihren Daten zu verbinden, und haben alle wichtigen KI-Apps in Hub, einschlie\u00dflich Nextcloud Assistant, vollst\u00e4ndig Open-Source-basiert entwickelt und f\u00fchren diese Apps lokal auf Ihrem Server aus. All das, damit Sie KI f\u00fcr Ihre privaten Aufgaben nutzen oder <a href=\"https:\/\/nextcloud.com\/blog\/integrating-ai-into-your-business-without-selling-your-data-to-big-tech\/\" target=\"_blank\" rel=\"noreferrer noopener\">in Ihr Unternehmen integrieren<\/a> k\u00f6nnen \u2013 ohne Ihre Daten an Big Tech zu weiterzugeben. <\/p>\n\n\n\n<p>Ihre Daten geh\u00f6ren Ihnen, und es werden keine Informationen an Drittanbieter weitergegeben, um die Leistung zu verbessern, das Benutzerverhalten zu untersuchen oder ein KI-Modell zu trainieren.<\/p>\n\n\n\n<p>Vielleicht m\u00f6chten Sie weiterhin beliebte Dienste wie ChatGPT und Dall-E nutzen? Dann geben wir Ihnen die Freiheit, dies in Nextcloud zu tun. Bevor Sie eine Entscheidung treffen, k\u00f6nnen Sie das <a href=\"https:\/\/nextcloud.com\/blog\/nextcloud-ethical-ai-rating\/\" target=\"_blank\" rel=\"noreferrer noopener\">Nextcloud Ethical AI Rating<\/a> zu Rate ziehen, um mehr dar\u00fcber zu erfahren, wie verf\u00fcgbare KI-Apps in Nextcloud Ihre Daten nutzen. Auf diese Weise k\u00f6nnen Sie auch die Risiken im Zusammenhang mit der Verf\u00fcgbarkeit von Code, den Bereitstellungsoptionen und dem Zugriff auf Trainingsdaten einsch\u00e4tzen. <\/p>\n\n\n\n<p>Wir ermutigen selbstverst\u00e4ndlich alle dazu, ethische <a href=\"https:\/\/nextcloud.com\/blog\/how-open-source-ai-models-can-help-you-take-control-of-your-privacy\/\" target=\"_blank\" rel=\"noreferrer noopener\">Open-Source<\/a>-KI-Modelle f\u00fcr ihre Arbeit zu nutzen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Souver\u00e4ne KI-Dienste<\/h2>\n\n\n\n<p>Wir arbeiten eng mit mehreren gro\u00dfen europ\u00e4ischen Hosting-Unternehmen zusammen, darunter IONOS, OVHcloud und plusserver, um die aktuellsten <a href=\"https:\/\/nextcloud.com\/blog\/press_releases\/europe-gearing-up-to-provide-ai-services\/\" target=\"_blank\" rel=\"noreferrer noopener\">KI-Dienste<\/a> dieser Unternehmen zu integrieren. Dadurch werden diese L\u00f6sungen den Kunden und Nutzern von Nextcloud zur Verf\u00fcgung stehen, die zwar die erweiterten KI-Funktionen von Nextcloud Hub nutzen, selbst jedoch keine KI-Dienste hosten m\u00f6chten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Die Zukunft: Spezialisierte KI f\u00fcr den \u00f6ffentlichen Sektor und dar\u00fcber hinaus<\/h2>\n\n\n\n<p>Die KI entwickelt sich rasant weiter. Eine Technologie, die k\u00fcnftig wichtig sein wird, sind Modelle zur Textgenerierung, die f\u00fcr bestimmte Aufgaben optimiert sind. Ein Beispiel ist der \u00f6ffentliche Sektor, in dem die Mitarbeitenden mit einer Vielzahl komplexer Formulare arbeiten.<\/p>\n\n\n\n<p>Gemeinsam mit dem Land Schleswig-Holstein arbeitet Nextcloud daran, ein digital souver\u00e4nes KI-Modell zu erstellen. Ziel ist es, die b\u00fcrokratischen Prozesse im \u00f6ffentlichen Sektor mit ethischen, KI-gest\u00fctzten Tools f\u00fcr die gemeinsame Erstellung von Inhalten zu beschleunigen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full imageRoundShadow\"><a href=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/09\/230919_Staatskanzlei_Nextcloud_1-scaled.jpg\"><img decoding=\"async\" width=\"2560\" height=\"1535\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/09\/230919_Staatskanzlei_Nextcloud_1-scaled.jpg\" alt=\"\" class=\"wp-image-143632\" srcset=\"https:\/\/nextcloud.com\/c\/uploads\/2023\/09\/230919_Staatskanzlei_Nextcloud_1-scaled.jpg 2560w, https:\/\/nextcloud.com\/c\/uploads\/2023\/09\/230919_Staatskanzlei_Nextcloud_1-300x180.jpg 300w, https:\/\/nextcloud.com\/c\/uploads\/2023\/09\/230919_Staatskanzlei_Nextcloud_1-961x576.jpg 961w, https:\/\/nextcloud.com\/c\/uploads\/2023\/09\/230919_Staatskanzlei_Nextcloud_1-768x461.jpg 768w, https:\/\/nextcloud.com\/c\/uploads\/2023\/09\/230919_Staatskanzlei_Nextcloud_1-1536x921.jpg 1536w, https:\/\/nextcloud.com\/c\/uploads\/2023\/09\/230919_Staatskanzlei_Nextcloud_1-2048x1228.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><figcaption class=\"wp-element-caption\">Der schleswig-holsteinische Minister f\u00fcr Digitalisierung und der CEO von Nextcloud reichen sich die Hand<\/figcaption><\/figure>\n\n\n\n<p>Das Projekt konzentriert sich auf die Entwicklung eines gro\u00dfen Sprachmodells, das auf die spezifischen Bed\u00fcrfnisse der Landesverwaltung zugeschnitten ist. Dies betrifft die Erstellung von stark standardisierten Texten unter Verwendung eines anerkannten Sprachstils und g\u00e4ngiger Formulierungen, die optimierte Suche nach prozessspezifischen Informationen und andere Aufgaben. Beim Training dieses Modells werden vom Land zur Verf\u00fcgung gestellte, anonymisierte Trainingsdaten verwendet.<\/p>\n\n\n\n<p>Das derzeit in Entwicklung befindliche Modell wird als Open Source ver\u00f6ffentlicht, um die Nutzung souver\u00e4ner und ethischer KI in den Digitalisierungsstrategien von Regierungen zu f\u00f6rdern. Die Funktion \u201eKontextuell Chatten\u201c ist ein erstes Ergebnis unserer Zusammenarbeit.<\/p>\n\n\n\n<p>In den kommenden Monaten und Jahren werden weitere optimierte KI-Modelle f\u00fcr Nextcloud ver\u00f6ffentlicht, die Mitarbeitenden in allen m\u00f6glichen Fachrichtungen bei ihren Aufgaben helfen.<\/p>\n\n\n<section class=\"promo-section   has_custom_bg_image hub25_cta full-width \" id=\"cta\" style=\"background-image: url(https:\/\/nextcloud.com\/c\/uploads\/2025\/08\/Nextcloud-Hub25Autumn-featured-image-final-bg.png);\" data-expiration=\"\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"text-block\">\n\t\t\t\t\t<h2>Sehen Sie sich den Launch von Nextcloud Hub 25 Autumn an<\/h2><p>Entdecken Sie Verbesserungen des Designs, intelligente neue Funktionen und eine schnellere Performance.<br \/>\nIhr digitaler Workspace \u2013 im Handumdrehen startklar<\/p>\n<a class=\"c-btn btn-white\" href=\"https:\/\/www.youtube.com\/watch?v=3jcYJGQgenI\" target=\"_blank\">Entdecken Sie die vollst\u00e4ndige Release<\/a>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n","protected":false},"excerpt":{"rendered":"<p>Der erste ethische Open-Source-KI-Assistent, der eine Vielzahl von Aufgaben f\u00fcr Sie erledigen kann, ohne Ihre Daten zu gef\u00e4hrden.<\/p>\n","protected":false},"author":33,"featured_media":146760,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"publish_to_discourse":"","publish_post_category":"22","wpdc_auto_publish_overridden":"","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"698655","discourse_permalink":"https:\/\/help.nextcloud.com\/t\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/235279","wpdc_publishing_response":"success","wpdc_publishing_error":"","footnotes":""},"categories":[372,276,220],"tags":[],"class_list":["post-349022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-blog-de","category-nachrichten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lernen Sie Nextcloud Assistant kennen - Nextcloud<\/title>\n<meta name=\"description\" content=\"Nextcloud pr\u00e4sentiert einen KI-Assistenten, der ethischen Grunds\u00e4tzen entspricht und Open-Source-basiert ist. Mit ihm k\u00f6nnen Sie eine Vielzahl von Aufgaben erledigen, ohne Ihre Daten zu gef\u00e4hrden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lernen Sie Nextcloud Assistant kennen - Nextcloud\" \/>\n<meta property=\"og:description\" content=\"Nextcloud pr\u00e4sentiert einen KI-Assistenten, der ethischen Grunds\u00e4tzen entspricht und Open-Source-basiert ist. Mit ihm k\u00f6nnen Sie eine Vielzahl von Aufgaben erledigen, ohne Ihre Daten zu gef\u00e4hrden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/\" \/>\n<meta property=\"og:site_name\" content=\"Nextcloud\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nextclouders\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-27T08:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-11T14:02:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nextcloud.com\/c\/uploads\/2023\/10\/Nextcloud-AI-Assistant-Hub-6-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mikhail Korotaev\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mikhail Korotaev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/\"},\"author\":{\"name\":\"Mikhail Korotaev\",\"@id\":\"https:\/\/nextcloud.com\/de\/#\/schema\/person\/c4131c923c11769c06b82290f98f8ac8\"},\"headline\":\"Der erste Open-Source-KI-Assistent, der Ihre Privatsph\u00e4re sch\u00fctzt\",\"datePublished\":\"2025-11-27T08:00:00+00:00\",\"dateModified\":\"2025-12-11T14:02:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/\"},\"wordCount\":1849,\"publisher\":{\"@id\":\"https:\/\/nextcloud.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nextcloud.com\/c\/uploads\/2023\/10\/Nextcloud-AI-Assistant-Hub-6.png\",\"articleSection\":{\"1\":\"Blog\",\"2\":\"Nachrichten\"},\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/\",\"url\":\"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/\",\"name\":\"Lernen Sie Nextcloud Assistant kennen - Nextcloud\",\"isPartOf\":{\"@id\":\"https:\/\/nextcloud.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nextcloud.com\/c\/uploads\/2023\/10\/Nextcloud-AI-Assistant-Hub-6.png\",\"datePublished\":\"2025-11-27T08:00:00+00:00\",\"dateModified\":\"2025-12-11T14:02:12+00:00\",\"description\":\"Nextcloud pr\u00e4sentiert einen KI-Assistenten, der ethischen Grunds\u00e4tzen entspricht und Open-Source-basiert ist. Mit ihm k\u00f6nnen Sie eine Vielzahl von Aufgaben erledigen, ohne Ihre Daten zu gef\u00e4hrden.\",\"breadcrumb\":{\"@id\":\"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/#primaryimage\",\"url\":\"https:\/\/nextcloud.com\/c\/uploads\/2023\/10\/Nextcloud-AI-Assistant-Hub-6.png\",\"contentUrl\":\"https:\/\/nextcloud.com\/c\/uploads\/2023\/10\/Nextcloud-AI-Assistant-Hub-6.png\",\"width\":1920,\"height\":1080,\"caption\":\"Meet the first open-source AI assistant that doesn't prey on your data\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nextcloud.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der erste Open-Source-KI-Assistent, der Ihre Privatsph\u00e4re sch\u00fctzt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nextcloud.com\/de\/#website\",\"url\":\"https:\/\/nextcloud.com\/de\/\",\"name\":\"Nextcloud\",\"description\":\"Regain control over your data\",\"publisher\":{\"@id\":\"https:\/\/nextcloud.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nextcloud.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nextcloud.com\/de\/#organization\",\"name\":\"Nextcloud\",\"url\":\"https:\/\/nextcloud.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/nextcloud.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg\",\"contentUrl\":\"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Nextcloud\"},\"image\":{\"@id\":\"https:\/\/nextcloud.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Nextclouders\/\",\"https:\/\/x.com\/nextclouders\",\"https:\/\/www.linkedin.com\/company\/10827569\/\",\"https:\/\/youtube.com\/nextcloud\",\"https:\/\/www.instagram.com\/nextclouders\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nextcloud.com\/de\/#\/schema\/person\/c4131c923c11769c06b82290f98f8ac8\",\"name\":\"Mikhail Korotaev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/nextcloud.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/50239e6d041bd078acdbbdad43132efabac4ca0799ae3eb97ec30bc09b62e515?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/50239e6d041bd078acdbbdad43132efabac4ca0799ae3eb97ec30bc09b62e515?s=96&d=mm&r=g\",\"caption\":\"Mikhail Korotaev\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lernen Sie Nextcloud Assistant kennen - Nextcloud","description":"Nextcloud pr\u00e4sentiert einen KI-Assistenten, der ethischen Grunds\u00e4tzen entspricht und Open-Source-basiert ist. Mit ihm k\u00f6nnen Sie eine Vielzahl von Aufgaben erledigen, ohne Ihre Daten zu gef\u00e4hrden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/","og_locale":"de_DE","og_type":"article","og_title":"Lernen Sie Nextcloud Assistant kennen - Nextcloud","og_description":"Nextcloud pr\u00e4sentiert einen KI-Assistenten, der ethischen Grunds\u00e4tzen entspricht und Open-Source-basiert ist. Mit ihm k\u00f6nnen Sie eine Vielzahl von Aufgaben erledigen, ohne Ihre Daten zu gef\u00e4hrden.","og_url":"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/","og_site_name":"Nextcloud","article_publisher":"https:\/\/www.facebook.com\/Nextclouders\/","article_published_time":"2025-11-27T08:00:00+00:00","article_modified_time":"2025-12-11T14:02:12+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/nextcloud.com\/c\/uploads\/2023\/10\/Nextcloud-AI-Assistant-Hub-6-1024x576.png","type":"image\/png"}],"author":"Mikhail Korotaev","twitter_misc":{"Verfasst von":"Mikhail Korotaev","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/#article","isPartOf":{"@id":"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/"},"author":{"name":"Mikhail Korotaev","@id":"https:\/\/nextcloud.com\/de\/#\/schema\/person\/c4131c923c11769c06b82290f98f8ac8"},"headline":"Der erste Open-Source-KI-Assistent, der Ihre Privatsph\u00e4re sch\u00fctzt","datePublished":"2025-11-27T08:00:00+00:00","dateModified":"2025-12-11T14:02:12+00:00","mainEntityOfPage":{"@id":"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/"},"wordCount":1849,"publisher":{"@id":"https:\/\/nextcloud.com\/de\/#organization"},"image":{"@id":"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/#primaryimage"},"thumbnailUrl":"https:\/\/nextcloud.com\/c\/uploads\/2023\/10\/Nextcloud-AI-Assistant-Hub-6.png","articleSection":{"1":"Blog","2":"Nachrichten"},"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/","url":"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/","name":"Lernen Sie Nextcloud Assistant kennen - Nextcloud","isPartOf":{"@id":"https:\/\/nextcloud.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/#primaryimage"},"image":{"@id":"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/#primaryimage"},"thumbnailUrl":"https:\/\/nextcloud.com\/c\/uploads\/2023\/10\/Nextcloud-AI-Assistant-Hub-6.png","datePublished":"2025-11-27T08:00:00+00:00","dateModified":"2025-12-11T14:02:12+00:00","description":"Nextcloud pr\u00e4sentiert einen KI-Assistenten, der ethischen Grunds\u00e4tzen entspricht und Open-Source-basiert ist. Mit ihm k\u00f6nnen Sie eine Vielzahl von Aufgaben erledigen, ohne Ihre Daten zu gef\u00e4hrden.","breadcrumb":{"@id":"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/#primaryimage","url":"https:\/\/nextcloud.com\/c\/uploads\/2023\/10\/Nextcloud-AI-Assistant-Hub-6.png","contentUrl":"https:\/\/nextcloud.com\/c\/uploads\/2023\/10\/Nextcloud-AI-Assistant-Hub-6.png","width":1920,"height":1080,"caption":"Meet the first open-source AI assistant that doesn't prey on your data"},{"@type":"BreadcrumbList","@id":"https:\/\/nextcloud.com\/de\/blog\/der-erste-open-source-ki-assistent-der-ihre-privatsphare-schutzt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nextcloud.com\/de\/"},{"@type":"ListItem","position":2,"name":"Der erste Open-Source-KI-Assistent, der Ihre Privatsph\u00e4re sch\u00fctzt"}]},{"@type":"WebSite","@id":"https:\/\/nextcloud.com\/de\/#website","url":"https:\/\/nextcloud.com\/de\/","name":"Nextcloud","description":"Regain control over your data","publisher":{"@id":"https:\/\/nextcloud.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nextcloud.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/nextcloud.com\/de\/#organization","name":"Nextcloud","url":"https:\/\/nextcloud.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nextcloud.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","contentUrl":"https:\/\/nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","width":"1024","height":"1024","caption":"Nextcloud"},"image":{"@id":"https:\/\/nextcloud.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Nextclouders\/","https:\/\/x.com\/nextclouders","https:\/\/www.linkedin.com\/company\/10827569\/","https:\/\/youtube.com\/nextcloud","https:\/\/www.instagram.com\/nextclouders\/"]},{"@type":"Person","@id":"https:\/\/nextcloud.com\/de\/#\/schema\/person\/c4131c923c11769c06b82290f98f8ac8","name":"Mikhail Korotaev","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nextcloud.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/50239e6d041bd078acdbbdad43132efabac4ca0799ae3eb97ec30bc09b62e515?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50239e6d041bd078acdbbdad43132efabac4ca0799ae3eb97ec30bc09b62e515?s=96&d=mm&r=g","caption":"Mikhail Korotaev"}}]}},"featured_media_url":"https:\/\/nextcloud.com\/c\/uploads\/2023\/10\/Nextcloud-AI-Assistant-Hub-6.png","_links":{"self":[{"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/posts\/349022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/comments?post=349022"}],"version-history":[{"count":8,"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/posts\/349022\/revisions"}],"predecessor-version":[{"id":359890,"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/posts\/349022\/revisions\/359890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/media\/146760"}],"wp:attachment":[{"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/media?parent=349022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/categories?post=349022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nextcloud.com\/de\/wp-json\/wp\/v2\/tags?post=349022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}